{"id":26790,"date":"2026-01-16T11:13:51","date_gmt":"2026-01-16T10:13:51","guid":{"rendered":"https:\/\/globalcitieshub.org\/?p=26790"},"modified":"2026-01-21T11:14:27","modified_gmt":"2026-01-21T10:14:27","slug":"high-level-panel-calls-for-coordinated-global-action-on-housing","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/","title":{"rendered":"Un groupe de haut niveau appelle \u00e0 une action mondiale coordonn\u00e9e en mati\u00e8re de logement"},"content":{"rendered":"<p>En amont de la <a href=\"https:\/\/wuf.unhabitat.org\/\">Forum urbain mondial 13 (FUM13)<\/a> qui se tiendra \u00e0 Bakou, Azerba\u00efdjan, du 17 au 22 mai 2026un panel de haut niveau sur <em>\"Faire face ensemble \u00e0 la crise mondiale du logement\".<\/em> s'est tenue \u00e0 Gen\u00e8ve, organis\u00e9e en partenariat avec UN-Habitat, l'Azerba\u00efdjan et d'autres partenaires.<\/p>\n\n\n\n<p>Mod\u00e9r\u00e9e par notre codirectrice Kamelia Kemileva, la session a r\u00e9uni des repr\u00e9sentants de haut niveau de UN Habitat (Anacl\u00e1udia Rossbach, directrice ex\u00e9cutive), d'Azerba\u00efdjan (Anar Guliyev, coordinateur national du FUM13), de la ville de Gen\u00e8ve (Alfonso G\u00f3mez, maire), de Belgique (Yves Leterme, ancien Premier ministre) et de Singapour (Penny Low, ancienne membre du Parlement), afin d'\u00e9changer sur les r\u00e9ponses syst\u00e9miques \u00e0 apporter \u00e0 la crise du logement dans le monde.<\/p>\n\n\n\n<p>Selon ONU-Habitat et d'autres sources des Nations unies, pr\u00e8s de trois milliards de personnes dans le monde vivent actuellement dans des conditions de logement inad\u00e9quates, dont plus d'un milliard dans des \u00e9tablissements informels. En outre, l'augmentation du co\u00fbt du logement, l'urbanisation rapide et les risques li\u00e9s au climat creusent les in\u00e9galit\u00e9s et exercent une pression croissante sur les villes et les syst\u00e8mes nationaux. Le panel a soulign\u00e9 que le logement ne peut plus \u00eatre trait\u00e9 comme une question sectorielle, mais doit \u00eatre abord\u00e9 comme une priorit\u00e9 essentielle de la politique publique li\u00e9e \u00e0 l'inclusion sociale, \u00e0 la r\u00e9silience et au d\u00e9veloppement durable.<\/p>\n\n\n\n<p>La discussion a mis en \u00e9vidence le r\u00f4le essentiel des gouvernements locaux et r\u00e9gionaux dans l'acc\u00e9l\u00e9ration de la fourniture de logements, tout en soulignant l'importance de cadres nationaux solides, de m\u00e9canismes de financement innovants et d'une gouvernance \u00e0 plusieurs niveaux. Le maire de Gen\u00e8ve a soulign\u00e9 que Gen\u00e8ve \u00e9tait \u00e9galement touch\u00e9e par la crise du logement. Il a \u00e9voqu\u00e9 certaines approches orient\u00e9es vers la recherche de solutions, telles que la possibilit\u00e9 pour les collectivit\u00e9s locales d'acqu\u00e9rir des propri\u00e9t\u00e9s et de construire des logements moins chers ou l'exemple m\u00eame du \"logement coop\u00e9ratif\" qui permet l'acc\u00e8s au logement et \u00e0 des prix mod\u00e9r\u00e9s pour les revenus moyens.<\/p>\n\n\n\n<p>Anaclaudia Rossbach, directrice ex\u00e9cutive de UN Habitat, a soulign\u00e9 l'importance du dialogue entre tous les niveaux de gouvernement. Elle a \u00e9galement mis l'accent sur l'importance strat\u00e9gique des <strong>FUM13<\/strong>sous le th\u00e8me <em>\"Loger le monde : Des villes et des communaut\u00e9s s\u00fbres et r\u00e9silientes\".<\/em> Le forum a \u00e9t\u00e9 pr\u00e9sent\u00e9 comme une plateforme mondiale unique permettant de galvaniser l'engagement politique, de favoriser les partenariats entre les secteurs et les r\u00e9gions et d'\u00e9laborer un appel \u00e0 l'action sur le logement, pr\u00e9par\u00e9 par les coorganisateurs.<\/p>\n\n\n\n<p>En conclusion, les pan\u00e9listes ont identifi\u00e9 les actions prioritaires \u00e0 mener d'ici le FUM13 et au-del\u00e0, en r\u00e9affirmant la n\u00e9cessit\u00e9 de placer le logement au c\u0153ur des strat\u00e9gies de d\u00e9veloppement national et urbain et de renforcer la collaboration \u00e0 tous les niveaux de gouvernance.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le GCH a anim\u00e9 une r\u00e9union d'information en amont du 13e Forum urbain mondial. Des repr\u00e9sentants de haut niveau, dont le directeur ex\u00e9cutif d'ONU-Habitat, ont soulign\u00e9 le r\u00f4le essentiel des gouvernements locaux et r\u00e9gionaux dans la fourniture de logements et ont insist\u00e9 sur l'importance de cadres nationaux solides, de m\u00e9canismes de financement innovants et d'une gouvernance \u00e0 plusieurs niveaux.<\/p>","protected":false},"author":1,"featured_media":26792,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[546,316,209,545],"class_list":["post-26790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-azerbaijan","tag-housing","tag-un-habitat","tag-wuf13"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>High-Level Panel Calls for Coordinated Global Action on Housing - Global Cities Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"High-Level Panel Calls for Coordinated Global Action on Housing - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"The GCH moderated a briefing ahead of the 13th World Urban Forum. High-level representatives, including UN-Habitat Executive Director, highlighted the critical role of local and regional governments in housing delivery and underscored the importance of strong national frameworks, innovative financing mechanisms and multilevel governance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-16T10:13:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T10:14:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/01\/Vignettes-News-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"root_new\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"root_new\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/\"},\"author\":{\"name\":\"root_new\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"High-Level Panel Calls for Coordinated Global Action on Housing\",\"datePublished\":\"2026-01-16T10:13:51+00:00\",\"dateModified\":\"2026-01-21T10:14:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/\"},\"wordCount\":375,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Vignettes-News-1.png\",\"keywords\":[\"Azerbaijan\",\"housing\",\"UN-Habitat\",\"WUF13\"],\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/\",\"name\":\"High-Level Panel Calls for Coordinated Global Action on Housing - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Vignettes-News-1.png\",\"datePublished\":\"2026-01-16T10:13:51+00:00\",\"dateModified\":\"2026-01-21T10:14:27+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/high-level-panel-calls-for-coordinated-global-action-on-housing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Vignettes-News-1.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Vignettes-News-1.png\",\"width\":786,\"height\":524},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"root_new\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"caption\":\"root_new\"},\"sameAs\":[\"http:\\\/\\\/gch.dev-bulbera.com\"],\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un panel de haut niveau appelle \u00e0 une action mondiale coordonn\u00e9e sur le logement - Global Cities Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/","og_locale":"fr_FR","og_type":"article","og_title":"High-Level Panel Calls for Coordinated Global Action on Housing - Global Cities Hub","og_description":"The GCH moderated a briefing ahead of the 13th World Urban Forum. High-level representatives, including UN-Habitat Executive Director, highlighted the critical role of local and regional governments in housing delivery and underscored the importance of strong national frameworks, innovative financing mechanisms and multilevel governance.","og_url":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/","og_site_name":"Global Cities Hub","article_published_time":"2026-01-16T10:13:51+00:00","article_modified_time":"2026-01-21T10:14:27+00:00","og_image":[{"width":786,"height":524,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/01\/Vignettes-News-1.png","type":"image\/png"}],"author":"root_new","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"\u00c9crit par":"root_new","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/"},"author":{"name":"root_new","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"High-Level Panel Calls for Coordinated Global Action on Housing","datePublished":"2026-01-16T10:13:51+00:00","dateModified":"2026-01-21T10:14:27+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/"},"wordCount":375,"publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/01\/Vignettes-News-1.png","keywords":["Azerbaijan","housing","UN-Habitat","WUF13"],"articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/","url":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/","name":"Un panel de haut niveau appelle \u00e0 une action mondiale coordonn\u00e9e sur le logement - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/01\/Vignettes-News-1.png","datePublished":"2026-01-16T10:13:51+00:00","dateModified":"2026-01-21T10:14:27+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/high-level-panel-calls-for-coordinated-global-action-on-housing\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/01\/Vignettes-News-1.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/01\/Vignettes-News-1.png","width":786,"height":524},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/fr\/#website","url":"https:\/\/globalcitieshub.org\/fr\/","name":"Global Cities Hub","description":"Relier les gouvernements locaux et r\u00e9gionaux aux Nations unies et \u00e0 d'autres organisations internationales","publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/fr\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"racine_nouveau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","url":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","caption":"root_new"},"sameAs":["http:\/\/gch.dev-bulbera.com"],"url":"https:\/\/globalcitieshub.org\/fr\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/26790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/comments?post=26790"}],"version-history":[{"count":1,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/26790\/revisions"}],"predecessor-version":[{"id":26793,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/26790\/revisions\/26793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media\/26792"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media?parent=26790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/categories?post=26790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/tags?post=26790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}