{"id":24771,"date":"2025-07-02T14:30:35","date_gmt":"2025-07-02T12:30:35","guid":{"rendered":"https:\/\/globalcitieshub.org\/?p=24771"},"modified":"2025-07-10T14:31:47","modified_gmt":"2025-07-10T12:31:47","slug":"gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/","title":{"rendered":"GCH plaide pour le financement de la localisation des ODD au FfD4 \u00e0 S\u00e9ville"},"content":{"rendered":"<p>Du 30 juin au 2 juillet 2025, GCH a particip\u00e9 \u00e0 la 4e Conf\u00e9rence internationale sur le financement du d\u00e9veloppement (FfD4) \u00e0 S\u00e9ville afin de promouvoir la localisation du financement du d\u00e9veloppement et un meilleur acc\u00e8s des gouvernements locaux et r\u00e9gionaux aux ressources financi\u00e8res nationales et internationales.<\/p>\n\n\n\n<p>Le FfD4 est un \u00e9v\u00e9nement pivot organis\u00e9 par les Nations unies pour \u00e9valuer et faire progresser la mise en \u0153uvre du Programme d'action d'Addis-Abeba, le cadre central du financement du d\u00e9veloppement durable. La conf\u00e9rence vise \u00e0 relever les d\u00e9fis mondiaux \u00e9mergents et \u00e0 mobiliser des ressources financi\u00e8res pour r\u00e9aliser le Programme de d\u00e9veloppement durable \u00e0 l'horizon 2030 et ses Objectifs de d\u00e9veloppement durable (ODD). Les GRL ont \u00e9t\u00e9 reconnus comme des parties prenantes importantes pour la localisation des ODD, mais ils manquent souvent des ressources financi\u00e8res n\u00e9cessaires pour agir.<\/p>\n\n\n\n<p>La GCH applaudit la <a href=\"https:\/\/financing.desa.un.org\/sites\/default\/files\/ffd4-documents\/2025\/Compromiso%20de%20Sevilla%20for%20action%2016%20June.pdf?_gl=1*67tjkz*_ga*MTExOTc3MzAyOS4xNzQzMTczMTQ3*_ga_TK9BQL5X7Z*czE3NTEzNTg1MzckbzckZzAkdDE3NTEzNTg1MzckajYwJGwwJGgw\">L'engagement de S\u00e9ville<\/a>le r\u00e9sultat officiel du FfD4, qui refl\u00e8te plusieurs recommandations des GRL dans le rapport \"<a href=\"https:\/\/globalcitieshub.org\/fr\/mayors-declaration-on-financing-for-development-to-build-a-better-more-equitable-world-for-future-generations\/\">D\u00e9claration des maires<\/a> sur le financement du d\u00e9veloppement afin de b\u00e2tir un monde meilleur et plus \u00e9quitable pour les g\u00e9n\u00e9rations futures\". Les \u00c9tats se sont engag\u00e9s \u00e0 renforcer les finances infranationales et les capacit\u00e9s des gouvernements locaux. Ils aideront les gouvernements locaux \u00e0 \u00e9tablir des priorit\u00e9s et \u00e0 renforcer leurs politiques. Ils invitent les banques multilat\u00e9rales de d\u00e9veloppement (BMD) \u00e0 mieux r\u00e9pondre aux besoins de d\u00e9veloppement local. Il est essentiel que les \u00c9tats aient d\u00e9cid\u00e9 de renforcer les architectures de coop\u00e9ration au d\u00e9veloppement aux niveaux national et mondial, y compris pour les gouvernements locaux.<\/p>\n\n\n\n<p><strong>Lib\u00e9rer le potentiel fiscal pour un d\u00e9veloppement urbain durable<\/strong><\/p>\n\n\n\n<p>Un panel sp\u00e9cial intitul\u00e9 \"Lib\u00e9rer le potentiel fiscal pour le d\u00e9veloppement urbain durable - Les voix des villes africaines pour mobiliser des ressources pour les ODD et les droits de l'homme\" sera organis\u00e9. <a href=\"https:\/\/au.int\/en\/agenda2063\/overview\">Agenda 2063<\/a>\"Le d\u00e9bat a explor\u00e9 la mani\u00e8re dont le financement des projets locaux devrait \u00eatre favoris\u00e9 dans le syst\u00e8me financier international, et comment les villes africaines r\u00e9forment leurs propres syst\u00e8mes financiers pour r\u00e9aliser les ODD et l'Agenda 2063. GCH a \u00e9t\u00e9 fi\u00e8re de contribuer \u00e0 la discussion en tant que membre d'un panel distingu\u00e9 comprenant :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>W. Mme Chilando Chitangala, maire de Lusaka, Zambie<\/li>\n\n\n\n<li>E. James Njoroge Muchiri, gouverneur adjoint, comt\u00e9 de Nairobi City, Kenya<\/li>\n\n\n\n<li>Noah Essapo Huguette, directeur du bureau du maire, mairie de Yaound\u00e9, Cameroun<\/li>\n\n\n\n<li>Eshetayehu Kinfu, chef du bureau du maire, administration de la ville d'Addis-Abeba, \u00c9thiopie<\/li>\n\n\n\n<li>Greg Munro, directeur, Cities Alliance<\/li>\n\n\n\n<li>Anacl\u00e0udia Rossbach, directrice ex\u00e9cutive de UN-Habitat<\/li>\n\n\n\n<li>Pradeep Kurukulasuriya, secr\u00e9taire ex\u00e9cutif du Fonds d'\u00e9quipement des Nations unies<\/li>\n\n\n\n<li>Hanan Morsy, Secr\u00e9taire ex\u00e9cutif adjoint de l'UNECA<\/li>\n\n\n\n<li>Gulnara Roll, chef de l'unit\u00e9 \"Villes\", PNUE<\/li>\n<\/ul>\n\n\n\n<p>La discussion a r\u00e9v\u00e9l\u00e9 l'importance de stabiliser et d'augmenter les sources de revenus nationales des villes, ce qui leur permet \u00e9galement d'avoir un meilleur acc\u00e8s aux financements et aux investissements internationaux. Un changement syst\u00e9mique au niveau local, national et international devrait aller de pair pour faire du d\u00e9veloppement local durable une r\u00e9alit\u00e9.<\/p>\n\n\n\n<p>Nous avons expliqu\u00e9 comment la GCH s'efforce de faire entendre la voix des GLR dans les n\u00e9gociations internationales sur le financement et le climat. Nous avons soulign\u00e9 l'importance d'inclure les villes dans les m\u00e9canismes de financement mondiaux et les processus d'\u00e9laboration des politiques d\u00e8s le d\u00e9part. Cette inclusion garantit que les politiques mondiales sont applicables sur le terrain.<\/p>\n\n\n\n<p>A cet \u00e9gard, nous avons pr\u00e9sent\u00e9 le processus de r\u00e9daction, avec le Parlement Mondial des Maires, de la \"D\u00e9claration des Maires sur le financement du d\u00e9veloppement pour construire un monde meilleur et plus \u00e9quitable pour les g\u00e9n\u00e9rations futures\" et de sa pr\u00e9sentation en tant que contribution aux n\u00e9gociations intergouvernementales. La d\u00e9claration des maires a \u00e9t\u00e9 pr\u00e9sent\u00e9e comme une contribution aux n\u00e9gociations intergouvernementales. <a href=\"https:\/\/globalcitieshub.org\/fr\/mayors-declaration-on-financing-for-development-to-build-a-better-more-equitable-world-for-future-generations\/\">D\u00e9claration des maires<\/a> reste ouvert \u00e0 la signature apr\u00e8s le FfD4.<\/p>\n\n\n\n<p><strong>Webinaire pr\u00e9paratoire GCH<\/strong><\/p>\n\n\n\n<p>Pendant les pr\u00e9paratifs du FfD4, la GCH a invit\u00e9 M. Mauricio Rodas, chef du secr\u00e9tariat de la Commission urbaine du SDSN, ancien maire de Quito, et Mme Karen Hitschke, PDG de Building Bridges, \u00e0 discuter des questions cl\u00e9s du financement durable et \u00e0 guider les participants au webinaire dans cette entreprise. Nous avons explor\u00e9 comment rendre l'architecture financi\u00e8re internationale plus apte \u00e0 financer des projets de d\u00e9veloppement local durable. Avec l'intensification du d\u00e9fi climatique, le resserrement de l'espace fiscal et les ODD encore loin d'\u00eatre atteints, la localisation du financement du d\u00e9veloppement est sans aucun doute l'un des principaux d\u00e9fis auxquels la communaut\u00e9 internationale est confront\u00e9e.<\/p>\n\n\n\n<p>Les intervenants ont d\u00e9battu de la n\u00e9cessit\u00e9 de localiser les financements en renfor\u00e7ant la coop\u00e9ration entre les gouvernements nationaux et locaux, les acteurs du secteur priv\u00e9 et les institutions financi\u00e8res internationales (IFI). Le syst\u00e8me financier international actuel, ax\u00e9 sur les \u00c9tats, doit \u00eatre adapt\u00e9 et l'acc\u00e8s local aux ressources financi\u00e8res mondiales doit \u00eatre rendu possible. Aujourd'hui, seuls 44% des \u00c9tats autorisent leurs collectivit\u00e9s territoriales \u00e0 emprunter de l'argent et seuls 10% des financements climatiques sont consacr\u00e9s \u00e0 des projets locaux.<\/p>\n\n\n\n<p>La coop\u00e9ration multi-niveaux et multilat\u00e9rale est d'une grande importance pour relier efficacement l'agenda mondial de la durabilit\u00e9 et sa mise en \u0153uvre au niveau local. Un plus grand engagement du secteur priv\u00e9 et la mobilisation des ressources des BMD pour soutenir les projets locaux de lutte contre le changement climatique pourraient ouvrir de nouvelles capacit\u00e9s. Cependant, cela n\u00e9cessite \u00e9galement des capacit\u00e9s ad\u00e9quates de la part des GRL pour d\u00e9velopper et g\u00e9rer des projets bancables, une bonne gouvernance transparente et un climat d'investissement stable bas\u00e9 sur des r\u00e8gles.<\/p>\n\n\n\n<p>Mauricio Rodas et Karen Hitschke ont expliqu\u00e9 comment des outils sp\u00e9cifiques pouvaient r\u00e9duire les risques d'investissement dans des projets locaux et am\u00e9liorer la solvabilit\u00e9 des GRL, en veillant \u00e0 ce qu'aucun endroit ne soit laiss\u00e9 pour compte. Plusieurs instruments de financement, tels que le financement catalytique, les fonds de garantie, le financement mixte et les partenariats public-priv\u00e9, ont \u00e9t\u00e9 identifi\u00e9s comme des outils efficaces. Il est essentiel d'augmenter le financement et les instruments de financement pour les GRL afin de s'assurer qu'ils peuvent payer leur juste part dans le financement des efforts locaux, y compris les projets sensibles au climat, et de faire avancer la r\u00e9alisation des ODD. Cela est particuli\u00e8rement pertinent pour l'ODD 13 \"Action pour le climat\" et l'ODD 11 \"Villes et communaut\u00e9s durables\".<\/p>\n\n\n\n<p><strong>Revoir le webinaire :<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"\u00c0 quoi s&#039;attendre lors de la conf\u00e9rence sur le financement du d\u00e9veloppement et au-del\u00e0 ?\" width=\"724\" height=\"407\" src=\"https:\/\/www.youtube.com\/embed\/13djWwaLp7E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Du 30 juin au 2 juillet 2025, GCH a particip\u00e9 \u00e0 la 4e Conf\u00e9rence internationale sur le financement du d\u00e9veloppement (FfD4) \u00e0 S\u00e9ville afin de promouvoir la localisation du financement du d\u00e9veloppement et un meilleur acc\u00e8s des gouvernements locaux et r\u00e9gionaux aux ressources financi\u00e8res nationales et internationales.<\/p>","protected":false},"author":1,"featured_media":24682,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[482,199,282,483,280,480,479,334,201,481,433],"class_list":["post-24771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-banks","tag-cities","tag-ffd4","tag-financial-institutions","tag-financing","tag-financing-for-development-conference","tag-funding","tag-regions","tag-sdgs","tag-sevilla","tag-sustainability"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GCH advocates for financing localization of SDGs at FfD4 in Sevilla - Global Cities Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GCH advocates for financing localization of SDGs at FfD4 in Sevilla - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"On 30 June \u2013 2 July 2025, GCH attended the 4th International Conference on Financing for Development (FfD4) in Sevilla to promote the localization of financing for development and better access of Local and Regional Governments (LRGs) to national and international financial resources.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-02T12:30:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-10T12:31:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/07\/Vignettes-News.png\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"root_new\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"root_new\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/\"},\"author\":{\"name\":\"root_new\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"GCH advocates for financing localization of SDGs at FfD4 in Sevilla\",\"datePublished\":\"2025-07-02T12:30:35+00:00\",\"dateModified\":\"2025-07-10T12:31:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/\"},\"wordCount\":841,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vignettes-News.png\",\"keywords\":[\"banks\",\"cities\",\"FfD4\",\"financial institutions\",\"financing\",\"Financing for Development Conference\",\"funding\",\"regions\",\"SDGs\",\"Sevilla\",\"sustainability\"],\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/\",\"name\":\"GCH advocates for financing localization of SDGs at FfD4 in Sevilla - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vignettes-News.png\",\"datePublished\":\"2025-07-02T12:30:35+00:00\",\"dateModified\":\"2025-07-10T12:31:47+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vignettes-News.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Vignettes-News.png\",\"width\":786,\"height\":524},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"root_new\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"caption\":\"root_new\"},\"sameAs\":[\"http:\\\/\\\/gch.dev-bulbera.com\"],\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GCH plaide pour le financement de la localisation des ODD au FfD4 \u00e0 S\u00e9ville - Global Cities Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/","og_locale":"fr_FR","og_type":"article","og_title":"GCH advocates for financing localization of SDGs at FfD4 in Sevilla - Global Cities Hub","og_description":"On 30 June \u2013 2 July 2025, GCH attended the 4th International Conference on Financing for Development (FfD4) in Sevilla to promote the localization of financing for development and better access of Local and Regional Governments (LRGs) to national and international financial resources.","og_url":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/","og_site_name":"Global Cities Hub","article_published_time":"2025-07-02T12:30:35+00:00","article_modified_time":"2025-07-10T12:31:47+00:00","og_image":[{"width":786,"height":524,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/07\/Vignettes-News.png","type":"image\/png"}],"author":"root_new","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"\u00c9crit par":"root_new","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/"},"author":{"name":"root_new","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"GCH advocates for financing localization of SDGs at FfD4 in Sevilla","datePublished":"2025-07-02T12:30:35+00:00","dateModified":"2025-07-10T12:31:47+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/"},"wordCount":841,"publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/07\/Vignettes-News.png","keywords":["banks","cities","FfD4","financial institutions","financing","Financing for Development Conference","funding","regions","SDGs","Sevilla","sustainability"],"articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/","url":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/","name":"GCH plaide pour le financement de la localisation des ODD au FfD4 \u00e0 S\u00e9ville - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/07\/Vignettes-News.png","datePublished":"2025-07-02T12:30:35+00:00","dateModified":"2025-07-10T12:31:47+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/gch-advocates-for-financing-localization-of-sdgs-at-ffd4-in-sevilla\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/07\/Vignettes-News.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/07\/Vignettes-News.png","width":786,"height":524},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/fr\/#website","url":"https:\/\/globalcitieshub.org\/fr\/","name":"Global Cities Hub","description":"Relier les gouvernements locaux et r\u00e9gionaux aux Nations unies et \u00e0 d'autres organisations internationales","publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/fr\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"racine_nouveau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","url":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","caption":"root_new"},"sameAs":["http:\/\/gch.dev-bulbera.com"],"url":"https:\/\/globalcitieshub.org\/fr\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/24771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/comments?post=24771"}],"version-history":[{"count":2,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/24771\/revisions"}],"predecessor-version":[{"id":24773,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/24771\/revisions\/24773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media\/24682"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media?parent=24771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/categories?post=24771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/tags?post=24771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}