{"id":24527,"date":"2025-06-10T10:47:48","date_gmt":"2025-06-10T08:47:48","guid":{"rendered":"https:\/\/globalcitieshub.org\/?p=24527"},"modified":"2025-06-10T10:55:19","modified_gmt":"2025-06-10T08:55:19","slug":"resilience-can-only-be-achieved-if-we-include-lrgs","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/","title":{"rendered":"La r\u00e9silience ne peut \u00eatre atteinte que si nous incluons les GRL."},"content":{"rendered":"<p>Plus de 3 000 participants se sont r\u00e9unis \u00e0 Gen\u00e8ve la semaine derni\u00e8re pour la 8e session de l'Assembl\u00e9e parlementaire du Conseil de l'Europe. <a href=\"https:\/\/globalplatform.undrr.org\/\">Plate-forme mondiale pour la r\u00e9duction des risques de catastrophes<\/a> (GPDRR), convoqu\u00e9e sous le th\u00e8me <em>\"Chaque jour compte : Agir pour la r\u00e9silience aujourd'hui\".<\/em> Des repr\u00e9sentants des gouvernements nationaux et locaux, des agences des Nations unies, de la soci\u00e9t\u00e9 civile et des experts en r\u00e9duction des risques de catastrophes se sont r\u00e9unis pour partager leurs connaissances, \u00e9valuer les tendances actuelles, identifier les lacunes et formuler des recommandations afin d'acc\u00e9l\u00e9rer la mise en \u0153uvre de la strat\u00e9gie de r\u00e9duction des risques de catastrophes. <a href=\"https:\/\/www.undrr.org\/implementing-sendai-framework\/what-sendai-framework\">Cadre de Sendai pour la r\u00e9duction des risques de catastrophes<\/a>.<\/p>\n\n\n\n<p>Le GPDRR a pr\u00e9sent\u00e9 un programme vari\u00e9 de sessions et d'\u00e9v\u00e9nements parall\u00e8les, en mettant l'accent sur le r\u00f4le des gouvernements locaux et r\u00e9gionaux dans la r\u00e9duction des risques de catastrophe (RRC). Les principales discussions ont port\u00e9 sur la gouvernance inclusive des risques de catastrophe, les solutions de financement pour la RRC locale, le renforcement des capacit\u00e9s locales et le renforcement de la r\u00e9silience urbaine. L'adoption g\u00e9n\u00e9ralis\u00e9e d'une approche \"de l'ensemble du gouvernement et de l'ensemble de la soci\u00e9t\u00e9\", qui a fa\u00e7onn\u00e9 \u00e0 la fois la participation et le r\u00e9cit de la plateforme, a \u00e9t\u00e9 un point fort r\u00e9current.<\/p>\n\n\n\n<p>La localisation du cadre de Sendai pour atteindre ses objectifs d'ici 2030 est apparue comme l'un des messages centraux de la semaine. Les <a href=\"https:\/\/www.undrr.org\/publication\/global-platform-2025-co-chairs-summary-geneva-call-disaster-risk-reduction\">R\u00e9sum\u00e9 des copr\u00e9sidents<\/a> - publi\u00e9 par le Bureau des Nations unies pour la r\u00e9duction des risques de catastrophe (UNDRR) et la Suisse - souligne que le renforcement de la r\u00e9silience est une responsabilit\u00e9 partag\u00e9e et que la multigouvernance en mati\u00e8re de RRC est essentielle pour garantir que les solutions sont inclusives, \u00e9quitables et transparentes. Il appelle \u00e9galement \u00e0 l'autonomisation des acteurs infranationaux et municipaux, soutenue par des ressources ad\u00e9quates, y compris un meilleur acc\u00e8s au financement local direct.<\/p>\n\n\n\n<p>Le cadre de Sendai reconna\u00eet depuis longtemps l'importance des gouvernements locaux et r\u00e9gionaux, appelant \u00e0 l'autonomisation des autorit\u00e9s locales avec des ressources, une capacit\u00e9 de prise de d\u00e9cision et une participation significative \u00e0 la RRC. \u00c0 ce titre, les collectivit\u00e9s territoriales sont de plus en plus reconnues comme faisant partie int\u00e9grante d'une gestion efficace des risques de catastrophe. Cette reconnaissance s'est clairement refl\u00e9t\u00e9e lors du GPDRR, o\u00f9 de nombreux repr\u00e9sentants de GRL du monde entier se sont r\u00e9unis et ont \u00e9t\u00e9 accueillis par le Global Cities Hub (GCH) et la Suisse pour un \u00e9v\u00e9nement de r\u00e9seautage d\u00e9di\u00e9.<\/p>\n\n\n\n<p>Dans sa d\u00e9claration en s\u00e9ance pl\u00e9ni\u00e8re, la codirectrice du GCH, Anh Thu Duong, a r\u00e9affirm\u00e9 que le cadre de Sendai se distingue des autres accords des Nations unies en reconnaissant explicitement le r\u00f4le central des organisations locales de d\u00e9veloppement. Elle a \u00e9galement soulign\u00e9 le d\u00e9fi persistant de l'acc\u00e8s limit\u00e9 au financement international auquel sont confront\u00e9s ces acteurs locaux. La quatri\u00e8me Conf\u00e9rence internationale sur le financement du d\u00e9veloppement (30 juin-3 juillet 2025, S\u00e9ville), qui se tiendra prochainement, offre une occasion unique de r\u00e9former l'architecture financi\u00e8re internationale et de faciliter l'acc\u00e8s des GRL aux ressources pour les initiatives locales de RRC et d'action climatique.<\/p>\n\n\n\n<p>Pour atteindre cet objectif, la GCH et le Parlement mondial des maires ont lanc\u00e9 l'initiative <a href=\"https:\/\/globalcitieshub.org\/fr\/mayors-declaration-on-financing-for-development-to-build-a-better-more-equitable-world-for-future-generations\/\">D\u00e9claration des maires sur le financement du d\u00e9veloppement pour construire un monde meilleur et plus \u00e9quitable pour les g\u00e9n\u00e9rations futures<\/a>. Cette d\u00e9claration appelle \u00e0 une collaboration plus \u00e9troite entre les collectivit\u00e9s locales, les gouvernements nationaux, les institutions financi\u00e8res internationales et le secteur priv\u00e9 afin de d\u00e9velopper des mod\u00e8les de financement innovants qui soutiendront des infrastructures r\u00e9silientes pour les g\u00e9n\u00e9rations futures. Tous les maires sont invit\u00e9s \u00e0 approuver et \u00e0 signer la d\u00e9claration.<\/p>\n\n\n\n<p>Alors que le monde est confront\u00e9 \u00e0 une escalade des risques climatiques et de catastrophes, le GPDRR a \u00e9t\u00e9 clair : une r\u00e9silience significative aux catastrophes ne peut \u00eatre obtenue qu'en travaillant main dans la main avec les acteurs locaux. L'\u00e9lan de Gen\u00e8ve doit maintenant se traduire par des actions concr\u00e8tes - mobiliser des financements, renforcer les capacit\u00e9s et faire entendre la voix des gouvernements locaux dans les forums d\u00e9cisionnels mondiaux. Ce n'est qu'\u00e0 cette condition que les objectifs du Cadre de Sendai pourront \u00eatre v\u00e9ritablement atteints d'ici \u00e0 2030.<\/p>","protected":false},"excerpt":{"rendered":"<p>Plus de 3 000 participants se sont r\u00e9unis \u00e0 Gen\u00e8ve la semaine derni\u00e8re pour la 8e session de la plate-forme mondiale pour la r\u00e9duction des risques de catastrophes (GPDRR). Un programme vari\u00e9 de sessions et d'\u00e9v\u00e9nements parall\u00e8les a \u00e9t\u00e9 mis en place, avec un accent particulier sur le r\u00f4le des gouvernements locaux et r\u00e9gionaux dans la r\u00e9duction des risques de catastrophes.<\/p>","protected":false},"author":1,"featured_media":24533,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resilience can only be achieved if we include LRGs - Global Cities Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resilience can only be achieved if we include LRGs - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"Over 3,000 participants gathered in Geneva last week for the 8th session of the Global Platform for Disaster Risk Reduction (GPDRR). It featured a diverse program of sessions and side-events, with a strong emphasis on the role of local and regional governments in disaster risk reduction.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-10T08:47:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-10T08:55:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/06\/Vignettes-News.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2456\" \/>\n\t<meta property=\"og:image:height\" content=\"1638\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"root_new\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"root_new\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/\"},\"author\":{\"name\":\"root_new\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"Resilience can only be achieved if we include LRGs\",\"datePublished\":\"2025-06-10T08:47:48+00:00\",\"dateModified\":\"2025-06-10T08:55:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/\"},\"wordCount\":522,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Vignettes-News.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/\",\"name\":\"Resilience can only be achieved if we include LRGs - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Vignettes-News.jpg\",\"datePublished\":\"2025-06-10T08:47:48+00:00\",\"dateModified\":\"2025-06-10T08:55:19+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/resilience-can-only-be-achieved-if-we-include-lrgs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Vignettes-News.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Vignettes-News.jpg\",\"width\":2456,\"height\":1638},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"root_new\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"caption\":\"root_new\"},\"sameAs\":[\"http:\\\/\\\/gch.dev-bulbera.com\"],\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9silience ne peut \u00eatre atteinte que si nous incluons les GRL - Global Cities Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/","og_locale":"fr_FR","og_type":"article","og_title":"Resilience can only be achieved if we include LRGs - Global Cities Hub","og_description":"Over 3,000 participants gathered in Geneva last week for the 8th session of the Global Platform for Disaster Risk Reduction (GPDRR). It featured a diverse program of sessions and side-events, with a strong emphasis on the role of local and regional governments in disaster risk reduction.","og_url":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/","og_site_name":"Global Cities Hub","article_published_time":"2025-06-10T08:47:48+00:00","article_modified_time":"2025-06-10T08:55:19+00:00","og_image":[{"width":2456,"height":1638,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/06\/Vignettes-News.jpg","type":"image\/jpeg"}],"author":"root_new","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"\u00c9crit par":"root_new","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/"},"author":{"name":"root_new","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"Resilience can only be achieved if we include LRGs","datePublished":"2025-06-10T08:47:48+00:00","dateModified":"2025-06-10T08:55:19+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/"},"wordCount":522,"publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/06\/Vignettes-News.jpg","articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/","url":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/","name":"La r\u00e9silience ne peut \u00eatre atteinte que si nous incluons les GRL - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/06\/Vignettes-News.jpg","datePublished":"2025-06-10T08:47:48+00:00","dateModified":"2025-06-10T08:55:19+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/resilience-can-only-be-achieved-if-we-include-lrgs\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/06\/Vignettes-News.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/06\/Vignettes-News.jpg","width":2456,"height":1638},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/fr\/#website","url":"https:\/\/globalcitieshub.org\/fr\/","name":"Global Cities Hub","description":"Relier les gouvernements locaux et r\u00e9gionaux aux Nations unies et \u00e0 d'autres organisations internationales","publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/fr\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"racine_nouveau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","url":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","caption":"root_new"},"sameAs":["http:\/\/gch.dev-bulbera.com"],"url":"https:\/\/globalcitieshub.org\/fr\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/24527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/comments?post=24527"}],"version-history":[{"count":1,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/24527\/revisions"}],"predecessor-version":[{"id":24531,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/24527\/revisions\/24531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media\/24533"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media?parent=24527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/categories?post=24527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/tags?post=24527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}