{"id":19066,"date":"2023-10-30T13:50:57","date_gmt":"2023-10-30T12:50:57","guid":{"rendered":"https:\/\/globalcitieshub.org\/?p=19066"},"modified":"2023-11-02T12:28:32","modified_gmt":"2023-11-02T11:28:32","slug":"peace-often-originates-at-the-local-level","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/","title":{"rendered":"La paix na\u00eet souvent au niveau local"},"content":{"rendered":"<p>Sami Kanaan, Pr\u00e9sident du Global Cities Hub, a ouvert la 10\u00e8me Semaine de la Paix de Gen\u00e8ve le 30 octobre. Son discours a soulign\u00e9 le r\u00f4le important des autorit\u00e9s locales dans le d\u00e9veloppement de communaut\u00e9s pacifiques.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/10\/image1-1.jpeg\" alt=\"\" class=\"wp-image-19087\" style=\"aspect-ratio:0.75;width:342px;height:auto\"\/><\/figure>\n<\/div>\n\n\n<p>La paix trouve souvent son origine au niveau local. Les villes sont les mieux plac\u00e9es pour mettre en \u0153uvre des mesures susceptibles de r\u00e9duire les causes profondes des conflits et de contribuer \u00e0 une soci\u00e9t\u00e9 plus pacifique. Il est essentiel d'investir dans l'\u00e9ducation, les soins de sant\u00e9 et l'int\u00e9gration sociale au niveau local pour limiter la violence urbaine.<\/p>\n\n\n\n<p><br>Alors que les villes manquent souvent de ressources, la collaboration internationale entre les villes et l'\u00e9change de connaissances sont d'autres \u00e9l\u00e9ments importants pour faire progresser le renforcement des capacit\u00e9s en vue de promouvoir la paix au niveau local. Les r\u00e9seaux de villes, les relations entre villes jumel\u00e9es et les plateformes de dialogue donnent aux villes la capacit\u00e9 de travailler ensemble, au-del\u00e0 des fronti\u00e8res nationales, pour construire un monde plus pacifique.<\/p>\n\n\n\n<p><br>Plusieurs \u00e9v\u00e9nements organis\u00e9s \u00e0 Gen\u00e8ve d\u00e9montrent d\u00e9j\u00e0 le r\u00f4le des gouvernements locaux dans la promotion de la paix. Les <a href=\"https:\/\/globalcitieshub.org\/fr\/the-forum-of-mayors\/\">Forum des Maires<\/a> (2-3 octobre 2023), le <a href=\"https:\/\/www.unhcr.org\/global-refugee-forum-2023\" target=\"_blank\" rel=\"noreferrer noopener\">Forum mondial des r\u00e9fugi\u00e9s<\/a> (13-15 d\u00e9cembre 2023) et le <a href=\"https:\/\/www.genevapeaceweek.ch\/en\" target=\"_blank\" rel=\"noreferrer noopener\">Semaine de la paix \u00e0 Gen\u00e8ve<\/a> (30 octobre-3 novembre 2023) sont des exemples de l'importance de relier les villes \u00e0 la communaut\u00e9 internationale.<br><\/p>\n\n\n\n<p>Le Global Cities Hub poursuivra son travail de mise en relation des gouvernements locaux et r\u00e9gionaux avec les Nations unies. Il s'agit notamment d'organiser des \u00e9v\u00e9nements pour r\u00e9unir des experts de <a href=\"https:\/\/www.geneve-int.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">La Gen\u00e8ve internationale<\/a> et des dirigeants locaux pour discuter des d\u00e9fis importants de notre \u00e9poque.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-vivid-red-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/10\/Geneva-Peace-Week.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Lire son discours ici<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Sami Kanaan, Pr\u00e9sident du Global Cities Hub, a ouvert la 10\u00e8me Semaine de la Paix de Gen\u00e8ve le 30 octobre. Son discours a soulign\u00e9 le r\u00f4le important des autorit\u00e9s locales dans le d\u00e9veloppement de communaut\u00e9s pacifiques. La paix na\u00eet souvent au niveau local. Les villes sont les mieux plac\u00e9es pour mettre en \u0153uvre des mesures qui peuvent r\u00e9duire les causes profondes des conflits et contribuer \u00e0 ... <\/p>","protected":false},"author":1,"featured_media":19067,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[142,1],"tags":[],"class_list":["post-19066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-international-geneva-news","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peace often originates at the local level - Global Cities Hub<\/title>\n<meta name=\"description\" content=\"Peace often originates at the local level. Cities are best positioned to implement measures that can contribute to a more peaceful society.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peace often originates at the local level - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"Peace often originates at the local level. Cities are best positioned to implement measures that can contribute to a more peaceful society.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T12:50:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-02T11:28:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/10\/News-8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"root_new\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"root_new\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/\"},\"author\":{\"name\":\"root_new\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"Peace often originates at the local level\",\"datePublished\":\"2023-10-30T12:50:57+00:00\",\"dateModified\":\"2023-11-02T11:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/News-8.png\",\"articleSection\":[\"International Geneva News\",\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/\",\"name\":\"Peace often originates at the local level - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/News-8.png\",\"datePublished\":\"2023-10-30T12:50:57+00:00\",\"dateModified\":\"2023-11-02T11:28:32+00:00\",\"description\":\"Peace often originates at the local level. Cities are best positioned to implement measures that can contribute to a more peaceful society.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/peace-often-originates-at-the-local-level\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/News-8.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/News-8.png\",\"width\":786,\"height\":524},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"root_new\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"caption\":\"root_new\"},\"sameAs\":[\"http:\\\/\\\/gch.dev-bulbera.com\"],\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La paix na\u00eet souvent au niveau local - Global Cities Hub","description":"La paix trouve souvent son origine au niveau local. Les villes sont les mieux plac\u00e9es pour mettre en \u0153uvre des mesures susceptibles de contribuer \u00e0 une soci\u00e9t\u00e9 plus pacifique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/","og_locale":"fr_FR","og_type":"article","og_title":"Peace often originates at the local level - Global Cities Hub","og_description":"Peace often originates at the local level. Cities are best positioned to implement measures that can contribute to a more peaceful society.","og_url":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/","og_site_name":"Global Cities Hub","article_published_time":"2023-10-30T12:50:57+00:00","article_modified_time":"2023-11-02T11:28:32+00:00","og_image":[{"width":786,"height":524,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/10\/News-8.png","type":"image\/png"}],"author":"root_new","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"\u00c9crit par":"root_new","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/"},"author":{"name":"root_new","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"Peace often originates at the local level","datePublished":"2023-10-30T12:50:57+00:00","dateModified":"2023-11-02T11:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/"},"wordCount":225,"publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/10\/News-8.png","articleSection":["International Geneva News","News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/","url":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/","name":"La paix na\u00eet souvent au niveau local - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/10\/News-8.png","datePublished":"2023-10-30T12:50:57+00:00","dateModified":"2023-11-02T11:28:32+00:00","description":"La paix trouve souvent son origine au niveau local. Les villes sont les mieux plac\u00e9es pour mettre en \u0153uvre des mesures susceptibles de contribuer \u00e0 une soci\u00e9t\u00e9 plus pacifique.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/peace-often-originates-at-the-local-level\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/10\/News-8.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/10\/News-8.png","width":786,"height":524},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/fr\/#website","url":"https:\/\/globalcitieshub.org\/fr\/","name":"Global Cities Hub","description":"Relier les gouvernements locaux et r\u00e9gionaux aux Nations unies et \u00e0 d'autres organisations internationales","publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/fr\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"racine_nouveau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","url":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","caption":"root_new"},"sameAs":["http:\/\/gch.dev-bulbera.com"],"url":"https:\/\/globalcitieshub.org\/fr\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/19066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/comments?post=19066"}],"version-history":[{"count":4,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/19066\/revisions"}],"predecessor-version":[{"id":19096,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/19066\/revisions\/19096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media\/19067"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media?parent=19066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/categories?post=19066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/tags?post=19066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}