{"id":16297,"date":"2022-03-16T11:40:00","date_gmt":"2022-03-16T10:40:00","guid":{"rendered":"https:\/\/www.genevacitieshub.org\/?p=16297"},"modified":"2022-03-29T15:08:04","modified_gmt":"2022-03-29T13:08:04","slug":"when-the-next-pandemic-comes-to-a-city","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/","title":{"rendered":"Quand la prochaine pand\u00e9mie arrive dans une ville..."},"content":{"rendered":"<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<p><strong>Le 16 mars 2022, <\/strong>le Geneva Cities Hub a organis\u00e9, en partenariat avec <a href=\"https:\/\/www.genevacitieshub.org\/en\/un-habitat\/\">ONU-Habitat,<\/a> un d\u00e9bat urbain \u00e0 Gen\u00e8ve pour mettre en avant les exp\u00e9riences municipales (Kigali-Rwanda, Madrid-Espagne, Niter\u00f3i-Br\u00e9sil et Cali-Colombie) pertinentes pour la prochaine pand\u00e9mie en termes de pr\u00e9vention, de pr\u00e9paration et de r\u00e9ponse.<\/p>\n\n\n\n<p>Pendant l'\u00e9v\u00e9nement, nous avons entendu <strong>recommandations <\/strong>d'\u00e9laborer ou de r\u00e9viser les politiques afin d'assurer une meilleure pr\u00e9paration aux futures urgences sanitaires :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Pr\u00e9parer une strat\u00e9gie de communication de crise plus efficace et plus cr\u00e9dible afin d'\u00e9viter la diffusion d'informations fausses et potentiellement dangereuses.<\/li><li>Impliquer d\u00e8s le d\u00e9but toutes les parties prenantes responsables de la protection de la sant\u00e9, de l'assistance sociale et de la relance \u00e9conomique.<\/li><li>Mieux harmoniser les politiques locales pour \u00e9viter la confusion de la population locale par les diff\u00e9rentes mesures en place.<\/li><li>Renforcer la coordination entre les acteurs internationaux, nationaux et locaux.<\/li><li>Mettre en place un m\u00e9canisme permanent de suivi et de r\u00e9action afin de r\u00e9agir plus rapidement et de mani\u00e8re plus structur\u00e9e.<\/li><\/ul>\n\n\n\n<p><strong>L'urbanisation massive r\u00e9cente a conduit les villes \u00e0<\/strong> <strong>deviennent des \u00e9picentres de la transmission des maladies.<\/strong> Les maladies infectieuses telles que le COVID-19, la tuberculose, la dengue et la diarrh\u00e9e se d\u00e9veloppent dans des environnements pauvres et surpeupl\u00e9s et sont \u00e9troitement li\u00e9es \u00e0 l'insalubrit\u00e9 des logements et \u00e0 une mauvaise gestion de l'assainissement et des d\u00e9chets. \u00c9tant donn\u00e9 que les villes sont concern\u00e9es par de nombreuses dimensions de la sant\u00e9, elles doivent \u00eatre impliqu\u00e9es non seulement dans la r\u00e9ponse aux pand\u00e9mies mais aussi dans le d\u00e9bat international sur le renforcement de la pr\u00e9paration. En raison de la proximit\u00e9 de leur population, de leur connaissance et de leur compr\u00e9hension des acteurs locaux et du contexte, les villes sont essentielles pour pr\u00e9venir les urgences sanitaires, s'y pr\u00e9parer et s'en remettre.<\/p>\n\n\n\n<p>Les maires et vice-maires de Kigali, Niter\u00f3i et Madrid ont expliqu\u00e9 la complexit\u00e9 de la r\u00e9ponse \u00e0 une pand\u00e9mie, en soulignant ses aspects de protection de la sant\u00e9, d'assistance sociale et de relance \u00e9conomique. <strong>Dr. Mpabwanamaguru Merard,<\/strong> vice-maire de Kigali, a parl\u00e9 de l'importance pour les gouvernements locaux de devenir la principale source d'information pour les citoyens, car personne n'est en s\u00e9curit\u00e9 tant que tout le monde ne l'est pas. <strong>Mme Bego\u00f1a Villac\u00eds Sanchez,<\/strong> maire adjoint de Madrid, a d\u00e9clar\u00e9 que les municipalit\u00e9s \u00e9taient les pierres angulaires de la r\u00e9ponse aux crises en raison de leur proximit\u00e9 avec les citoyens. L'adjoint au maire nous a parl\u00e9 de 105 investissements transformateurs dans le cadre d'un plan visant \u00e0 rendre la ville de Madrid plus r\u00e9siliente \u00e0 l'avenir. <strong>M. Axel Grael,<\/strong> maire de Niter\u00f3i, a plaid\u00e9 pour une meilleure communication entre les villes afin que les gens ne soient pas d\u00e9rout\u00e9s par des informations et des r\u00e9glementations locales diff\u00e9rentes. Les participants ont convenu que Covid-19 avait chang\u00e9 tous les aspects de notre vie, en particulier la vie urbaine.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.genevacitieshub.org\/wp-content\/uploads\/2022\/03\/GUD-urban-health-pandemics-3.jpg\" alt=\"\" class=\"wp-image-16309\"\/><figcaption>L'\u00e9v\u00e9nement hybride a eu lieu \u00e0 la Villa Rigot.<\/figcaption><\/figure><\/div>\n\n\n\n<p>L'OMS et ONU-Habitat ont expliqu\u00e9 les efforts en cours au niveau mondial. <strong>M. Graham Alabaster,<\/strong> chef du bureau d'ONU-Habitat \u00e0 Gen\u00e8ve, a d\u00e9clar\u00e9 que pour que les efforts de pr\u00e9paration et de r\u00e9ponse \u00e0 une pand\u00e9mie soient couronn\u00e9s de succ\u00e8s, nous devons harmoniser les r\u00e8gles de base de la gestion des urgences. <strong>Mme Nathalie Roebbel,<\/strong> chef d'unit\u00e9 \u00e0 l'OMS, a expliqu\u00e9 les nombreuses composantes de la sant\u00e9 urbaine et la n\u00e9cessit\u00e9 de relier les diff\u00e9rents points d'entr\u00e9e des politiques sociales, environnementales et \u00e9conomiques aux niveaux international, national et local. <strong>M. Ludy Prapancha Suryantoro,<\/strong> chef d'unit\u00e9 \u00e0 l'OMS, a soulign\u00e9 que la pr\u00e9paration aux situations d'urgence n\u00e9cessite une approche gouvernementale et sociale globale. A ce titre, il a rappel\u00e9 que l'OMS, dans sa r\u00e9solution <a href=\"https:\/\/apps.who.int\/gb\/ebwha\/pdf_files\/WHA73\/A73_R8-en.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">WHA73\/8 de 2020 sur le renforcement de la pr\u00e9paration aux urgences sanitaires<\/a> incluent d\u00e9j\u00e0 les villes. Les villes sont au c\u0153ur de la pr\u00e9paration et de la r\u00e9ponse aux pand\u00e9mies, et les villes internationales deviennent de plus en plus importantes de ce point de vue.<\/p>\n\n\n\n<p><strong>M. Jos\u00e9 Alvarez <\/strong>de CGLU a d\u00e9crit le travail important r\u00e9alis\u00e9 par son organisation en coop\u00e9ration avec les villes sur les questions de sant\u00e9, en particulier pour maintenir la conversation \u00e0 plusieurs niveaux. R\u00e9cemment, CGLU a mis l'accent sur le partage d'exp\u00e9riences locales concernant les d\u00e9fis de l'acc\u00e8s aux vaccins. Le point de vue acad\u00e9mique a \u00e9t\u00e9 pr\u00e9sent\u00e9 par <strong>Mme Lyda Osorio <\/strong>de l'Universidad del Valle Cali, en Colombie, qui s'est concentr\u00e9e sur les d\u00e9terminants sociaux de la sant\u00e9 et la complexit\u00e9 de la r\u00e9ponse \u00e0 la pand\u00e9mie. Elle a soulign\u00e9 avec \u00e9loquence que les autorit\u00e9s locales devaient ajuster en permanence l'objectif premier de l'intervention - qu'il s'agisse de la protection de la sant\u00e9, de l'aide sociale ou de la relance \u00e9conomique. <strong>M. Nicolas Gharbi, <\/strong>conseiller principal \u00e0 la ville de Madrid, a conclu en invitant toutes les parties prenantes \u00e0 faire progresser la coop\u00e9ration entre villes, qui s'est av\u00e9r\u00e9e cruciale lors de la derni\u00e8re pand\u00e9mie, et \u00e0 renforcer la coordination entre les acteurs internationaux, nationaux et locaux.<\/p>\n\n\n\n<p>Ce d\u00e9bat urbain de Gen\u00e8ve a prouv\u00e9 l'importance du travail municipal pour faire face \u00e0 la pand\u00e9mie de Covid-19 et le r\u00f4le des autorit\u00e9s locales dans la pr\u00e9vention et la r\u00e9ponse \u00e0 d'\u00e9ventuelles pand\u00e9mies futures. La participation de plusieurs parties prenantes a mis en lumi\u00e8re des aspects importants de la sant\u00e9 urbaine, notamment la pr\u00e9paration et la r\u00e9ponse aux pand\u00e9mies. Comme l'a dit M. Alabaster : \"<em>lorsque la prochaine pand\u00e9mie frappera une ville, la gravit\u00e9 de ses effets d\u00e9pendra \u00e9galement des conditions sanitaires g\u00e9n\u00e9rales de la ville.<\/em>\". Il est donc de la plus haute importance de renforcer l'inclusion des villes et des gouvernements locaux dans les d\u00e9bats intergouvernementaux tenus \u00e0 l'OMS sur la pr\u00e9paration et la r\u00e9ponse aux pand\u00e9mies.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Vid\u00e9o<\/strong><\/h5>\n\n\n\n<p>Regardez le&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=sGAzXcr_lhs\" target=\"_blank\" rel=\"noreferrer noopener\">vid\u00e9o<\/a>&nbsp;de l'\u00e9v\u00e9nement.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le 16 mars 2022, le Geneva Cities Hub a organis\u00e9, en partenariat avec UN-Habitat, un d\u00e9bat urbain \u00e0 Gen\u00e8ve pour mettre en avant les exp\u00e9riences municipales (Kigali-Rwanda, Madrid-Espagne, Niter\u00f3i-Br\u00e9sil et Cali-Colombie) pertinentes pour la prochaine pand\u00e9mie en termes de pr\u00e9vention, de pr\u00e9paration et de r\u00e9ponse. Au cours de l'\u00e9v\u00e9nement, nous avons entendu des recommandations pour d\u00e9velopper ou r\u00e9viser les politiques ... <\/p>","protected":false},"author":1,"featured_media":16304,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-16297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>When the next pandemic comes to a city\u2026 - Global Cities Hub<\/title>\n<meta name=\"description\" content=\"We organized a Geneva Urban Debate to share municipal experiences for the prevention, preparedness and response of the next pandemic.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"When the next pandemic comes to a city\u2026 - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"We organized a Geneva Urban Debate to share municipal experiences for the prevention, preparedness and response of the next pandemic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-16T10:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-29T13:08:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2022\/03\/GUD-on-Health-news.png\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"root_new\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"root_new\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/\"},\"author\":{\"name\":\"root_new\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"When the next pandemic comes to a city\u2026\",\"datePublished\":\"2022-03-16T10:40:00+00:00\",\"dateModified\":\"2022-03-29T13:08:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/\"},\"wordCount\":785,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/GUD-on-Health-news.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/\",\"name\":\"When the next pandemic comes to a city\u2026 - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/GUD-on-Health-news.png\",\"datePublished\":\"2022-03-16T10:40:00+00:00\",\"dateModified\":\"2022-03-29T13:08:04+00:00\",\"description\":\"We organized a Geneva Urban Debate to share municipal experiences for the prevention, preparedness and response of the next pandemic.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/when-the-next-pandemic-comes-to-a-city\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/GUD-on-Health-news.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/GUD-on-Health-news.png\",\"width\":786,\"height\":524},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"root_new\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"caption\":\"root_new\"},\"sameAs\":[\"http:\\\/\\\/gch.dev-bulbera.com\"],\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quand la prochaine pand\u00e9mie touchera une ville... - Global Cities Hub","description":"Nous avons organis\u00e9 un d\u00e9bat urbain \u00e0 Gen\u00e8ve afin de partager les exp\u00e9riences municipales en mati\u00e8re de pr\u00e9vention, de pr\u00e9paration et de r\u00e9ponse \u00e0 la prochaine pand\u00e9mie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/","og_locale":"fr_FR","og_type":"article","og_title":"When the next pandemic comes to a city\u2026 - Global Cities Hub","og_description":"We organized a Geneva Urban Debate to share municipal experiences for the prevention, preparedness and response of the next pandemic.","og_url":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/","og_site_name":"Global Cities Hub","article_published_time":"2022-03-16T10:40:00+00:00","article_modified_time":"2022-03-29T13:08:04+00:00","og_image":[{"width":786,"height":524,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2022\/03\/GUD-on-Health-news.png","type":"image\/png"}],"author":"root_new","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"\u00c9crit par":"root_new","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/"},"author":{"name":"root_new","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"When the next pandemic comes to a city\u2026","datePublished":"2022-03-16T10:40:00+00:00","dateModified":"2022-03-29T13:08:04+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/"},"wordCount":785,"publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2022\/03\/GUD-on-Health-news.png","articleSection":["News"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/","url":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/","name":"Quand la prochaine pand\u00e9mie touchera une ville... - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2022\/03\/GUD-on-Health-news.png","datePublished":"2022-03-16T10:40:00+00:00","dateModified":"2022-03-29T13:08:04+00:00","description":"Nous avons organis\u00e9 un d\u00e9bat urbain \u00e0 Gen\u00e8ve afin de partager les exp\u00e9riences municipales en mati\u00e8re de pr\u00e9vention, de pr\u00e9paration et de r\u00e9ponse \u00e0 la prochaine pand\u00e9mie.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/when-the-next-pandemic-comes-to-a-city\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2022\/03\/GUD-on-Health-news.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2022\/03\/GUD-on-Health-news.png","width":786,"height":524},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/fr\/#website","url":"https:\/\/globalcitieshub.org\/fr\/","name":"Global Cities Hub","description":"Relier les gouvernements locaux et r\u00e9gionaux aux Nations unies et \u00e0 d'autres organisations internationales","publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/fr\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"racine_nouveau","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","url":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","caption":"root_new"},"sameAs":["http:\/\/gch.dev-bulbera.com"],"url":"https:\/\/globalcitieshub.org\/fr\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/16297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/comments?post=16297"}],"version-history":[{"count":10,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/16297\/revisions"}],"predecessor-version":[{"id":16510,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/posts\/16297\/revisions\/16510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media\/16304"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media?parent=16297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/categories?post=16297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/tags?post=16297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}