{"id":545,"date":"2016-10-14T09:44:04","date_gmt":"2016-10-14T09:44:04","guid":{"rendered":"http:\/\/demowp.cththemes.net\/diopter\/?page_id=545"},"modified":"2024-11-13T11:00:19","modified_gmt":"2024-11-13T10:00:19","slug":"global-cities-hub-home","status":"publish","type":"page","link":"https:\/\/globalcitieshub.org\/fr\/","title":{"rendered":"Global Cities Hub"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"545\" class=\"elementor elementor-545\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12d5345 elementor-section-full_width overvi pad-bot-0 pad-top-0 elementor-section-height-default elementor-section-height-default\" data-id=\"12d5345\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ddf51e\" data-id=\"8ddf51e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-611b4d6 elementor-widget elementor-widget-hero_section\" data-id=\"611b4d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hero_section.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <section class=\"scroll-con-sec hero-section elementor-hero-section\" data-scrollax-parent=\"true\">\r\n                            <div class=\"hero-bg-wrap hero-bg-absolute\"><div class=\"bg\" style=\"background-image:url(https:\/\/globalcitieshub.org\/wp-content\/uploads\/2022\/08\/Homepage-Banner.png);\"  data-bg=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2022\/08\/Homepage-Banner.png\" data-scrollax=\"properties: { translateY: '200px' }\"><\/div><\/div>\r\n                        <div class=\"overlay\" style=\"opacity:0.5;\"><\/div>\r\n            <div class=\"hero-section-wrap fl-wrap\">\r\n                <div class=\"container small-container\">\r\n                                        <div class=\"intro-item fl-wrap\">\r\n                            <span class=\"section-separator\"><\/span>\n<div>\n     <h1>Global Cities Hub<\/h1>\n<h4><span style=\"color: rgb(255, 255, 255);\">Connecter les gouvernements locaux et r\u00e9gionaux aux Nations unies et \u00e0 d'autres organisations internationales  <br>&nbsp;                    <\/div>\r\n                                                                                \r\n                                        \r\n                                    <\/div>\r\n            <\/div>\r\n            <!-- <div class=\"bubble-bg\"> <\/div> -->\r\n                            <div class=\"header-sec-link\">\r\n                    <a href=\"#events\" class=\"custom-scroll-link\"><i class=\"fal fa-angle-double-down\"><\/i><\/a>\r\n                <\/div>\r\n                    <\/section>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac743bf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ac743bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9604cf5\" data-id=\"9604cf5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f2352c elementor-widget elementor-widget-section_title\" data-id=\"8f2352c\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"events\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"section-title section-title-dk-blue fl-wrap\">\r\n                        <h2><span>A LA UNE<\/span><\/h2>                                        <span class=\"section-separator section-separator-dk-blue\"><\/span> \r\n                         \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed103c3 elementor-widget elementor-widget-listings_grid_new\" data-id=\"ed103c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"listings_grid_new.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <!-- carousel -->\r\n        <div class=\"listings-grid-wrap clearfix three-cols\">\r\n\r\n\r\n                <!-- list-main-wrap-->\r\n                <div class=\"list-main-wrap fl-wrap card-listing cthiso-isotope-wrapper\">\r\n\r\n                    <div class=\"container\">\r\n                        <div class=\"row\">\r\n\r\n                            <div class=\"col-md-12\">\r\n\r\n                                \r\n                                <div class=\"cthiso-items cthiso-small-pad cthiso-three-cols clearfix cthiso-flexes\">\r\n                                    <div class=\"cthiso-sizer\"><\/div>\r\n                                    \r\n<!-- listing-item -->\r\n<div class=\"cthiso-item listing-item-loop post-27749 listing type-listing status-publish has-post-thumbnail hentry\"  data-postid=\"27749\">\r\n    <article class=\"geodir-category-listing fl-wrap\">\r\n        <div class=\"azp_element preview_listing azp-element-azp-2kxm7x7j47m geodir-category-img event card-hide-overlay\" >\r\n        <div class=\"geodir-js-favorite_btn\">\r\n                    <a href=\"#\" class=\"save-btn logreg-modal-open\" data-message=\"Logging in first to save this listing.\"><i class=\"fal fa-heart\"><\/i><span>Sauvez<\/span><\/a>\r\n            <\/div>\r\n    \r\n            \r\n\r\n    <a href=\"https:\/\/globalcitieshub.org\/fr\/13th-world-urban-forum-multilevel-cooperation-for-sustainable-urbanization\/\" class=\"listing-thumb-link geodir-category-img-wrap fl-wrap\">\r\n        \r\n        <img fetchpriority=\"high\" width=\"424\" height=\"280\" class=\"respimg lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/05\/vignette_news_WUF-424x280.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/05\/vignette_news_WUF-424x280.png\" \/>\r\n            <\/a>\r\n        <div class=\"listing-avatar\"><a href=\"https:\/\/globalcitieshub.org\/fr\/author\/root_new\/\"><img alt='racine_nouveau' src='https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg' class='avatar avatar-80 photo' height='80' width='80' \/><\/a>\r\n        <span class=\"avatar-tooltip lpre-avatar\">Ajout\u00e9 par <strong>racine_nouveau<\/strong><\/span>\r\n    <\/div>\r\n    \r\n    \r\n     \r\n\r\n    \r\n    \r\n    \r\n    \r\n     \r\n          \r\n        <div class=\"lcfields-wrap dis-flex\"><\/div>\r\n    \r\n<\/div>\r\n<div class=\"azp_element preview_listing_content azp-element-azp-ggr3yufgsme geodir-category-content\" >\r\n\r\n    \r\n    <div class=\"geodir-category-content-title fl-wrap\">\r\n        <div class=\"geodir-category-content-title-item\">\r\n            <h3 class=\"title-sin_map\">\r\n                                <a href=\"https:\/\/globalcitieshub.org\/fr\/13th-world-urban-forum-multilevel-cooperation-for-sustainable-urbanization\/\">13e Forum urbain mondial : coop\u00e9ration \u00e0 plusieurs niveaux pour une urbanisation durable<\/a>\r\n                            <\/h3>\r\n            <div class=\"geodir-category-location fl-wrap\"><a href=\"#\" class=\"map-item\" target=\"_blank\"><i class=\"fas fa-map-marker-alt\"><\/i><\/a><\/div>        <\/div>\r\n    <\/div>\r\n    <div class=\"geodir-category-text fl-wrap\">\r\n                        <div class=\"lcfields-wrap dis-flex\"><div class=\"azp_element lcustom_field lcfield-short_description ftitle-block-no azp-element-azp-3kx10ozfstc lcfield-wid-12 lcus-field-type-dflt lcus-sec-style-no authplan-hide-false\">\r\n    <div class=\"for-hide-on-author\"><\/div>\r\n                <div class=\"lcfield-inner\">\r\n                                                            <span class=\"lcfield-value\">Le Global Cities Hub participera au 13e Forum urbain mondial. En tant que l'un des principaux rassemblements mondiaux sur l'urbanisation durable, le FUM offre une plateforme pour \u00e9changer des exp\u00e9riences, renforcer la coop\u00e9ration \u00e0 plusieurs niveaux et faire avancer les solutions pour l'avenir des villes. Nous attendons avec impatience un FUM inspirant et orient\u00e9 vers l'action, avec l'engagement des gouvernements locaux et r\u00e9gionaux.<\/span>\r\n                                    <\/div>\r\n    <\/div>\r\n<\/div>\r\n            <\/div>\r\n    <\/div>\r\n    <\/article>\r\n<\/div>\r\n<!-- listing-item end-->  \r\n<!-- listing-item -->\r\n<div class=\"cthiso-item listing-item-loop post-27567 listing type-listing status-publish has-post-thumbnail hentry listing_tag-cities listing_tag-climate listing_tag-climate-change listing_tag-cooperation listing_tag-environment listing_tag-environmental-governance listing_tag-geneva listing_tag-health listing_tag-regions listing_tag-sustainability listing_tag-sustainable-development listing_tag-unep listing_tag-who listing_tag-world-health-assembly\"  data-postid=\"27567\">\r\n    <article class=\"geodir-category-listing fl-wrap\">\r\n        <div class=\"azp_element preview_listing azp-element-azp-2kxm7x7j47m geodir-category-img event card-hide-overlay\" >\r\n        <div class=\"geodir-js-favorite_btn\">\r\n                    <a href=\"#\" class=\"save-btn logreg-modal-open\" data-message=\"Logging in first to save this listing.\"><i class=\"fal fa-heart\"><\/i><span>Sauvez<\/span><\/a>\r\n            <\/div>\r\n    \r\n            \r\n\r\n    <a href=\"https:\/\/globalcitieshub.org\/fr\/localizing-the-climate-change-and-health-agenda-is-essential\/\" class=\"listing-thumb-link geodir-category-img-wrap fl-wrap\">\r\n        \r\n        <img width=\"424\" height=\"280\" class=\"respimg lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/04\/vignette_event_WHA.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/04\/vignette_event_WHA.png\" \/>\r\n            <\/a>\r\n        <div class=\"listing-avatar\"><a href=\"https:\/\/globalcitieshub.org\/fr\/author\/root_new\/\"><img alt='racine_nouveau' src='https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg' class='avatar avatar-80 photo' height='80' width='80' \/><\/a>\r\n        <span class=\"avatar-tooltip lpre-avatar\">Ajout\u00e9 par <strong>racine_nouveau<\/strong><\/span>\r\n    <\/div>\r\n    \r\n    \r\n     \r\n\r\n    \r\n    \r\n    \t<div class=\"geodir_status_date lstatus-opening\"><i class=\"fal fa-clock\"><\/i>20 mai 2026 18:00<\/div>\r\n\t\r\n    \r\n     \r\n      \r\n        <div class=\"lcfields-wrap dis-flex\"><\/div>\r\n    \r\n<\/div>\r\n<div class=\"azp_element preview_listing_content azp-element-azp-ggr3yufgsme geodir-category-content\" >\r\n\r\n    \r\n    <div class=\"geodir-category-content-title fl-wrap\">\r\n        <div class=\"geodir-category-content-title-item\">\r\n            <h3 class=\"title-sin_map\">\r\n                                <a href=\"https:\/\/globalcitieshub.org\/fr\/localizing-the-climate-change-and-health-agenda-is-essential\/\">Changement climatique, sant\u00e9 et villes - Des engagements mondiaux \u00e0 l'impact local<\/a>\r\n                            <\/h3>\r\n            <div class=\"geodir-category-location fl-wrap\"><a href=\"#\" class=\"map-item\" target=\"_blank\"><i class=\"fas fa-map-marker-alt\"><\/i>Villa Rigot &amp; en ligne<\/a><\/div>        <\/div>\r\n    <\/div>\r\n    <div class=\"geodir-category-text fl-wrap\">\r\n                        <div class=\"lcfields-wrap dis-flex\"><div class=\"azp_element lcustom_field lcfield-short_description ftitle-block-no azp-element-azp-3kx10ozfstc lcfield-wid-12 lcus-field-type-dflt lcus-sec-style-no authplan-hide-false\">\r\n    <div class=\"for-hide-on-author\"><\/div>\r\n                <div class=\"lcfield-inner\">\r\n                                                            <span class=\"lcfield-value\">Le changement climatique est l'une des menaces les plus importantes pour la sant\u00e9 publique au 21e si\u00e8cle. Cet \u00e9v\u00e9nement explorera comment la localisation et la coop\u00e9ration \u00e0 plusieurs niveaux sont essentielles pour faire face aux impacts du changement climatique sur la sant\u00e9 et pour atteindre les objectifs du Plan d'action mondial sur le changement climatique et la sant\u00e9.<\/span>\r\n                                    <\/div>\r\n    <\/div>\r\n<\/div>\r\n            <\/div>\r\n        <div class=\"geodir-category-footer fl-wrap dis-flex\">\r\n                        <div class=\"geodir-opt-list dis-flex\">\r\n            <ul class=\"no-list-style\">\r\n                                                                                            <\/ul>\r\n        <\/div>\r\n            <\/div>\r\n    <\/div>\r\n    <\/article>\r\n<\/div>\r\n<!-- listing-item end-->  \r\n<!-- listing-item -->\r\n<div class=\"cthiso-item listing-item-loop post-27691 listing type-listing status-publish has-post-thumbnail hentry\"  data-postid=\"27691\">\r\n    <article class=\"geodir-category-listing fl-wrap\">\r\n        <div class=\"azp_element preview_listing azp-element-azp-2kxm7x7j47m geodir-category-img event card-hide-overlay\" >\r\n        <div class=\"geodir-js-favorite_btn\">\r\n                    <a href=\"#\" class=\"save-btn logreg-modal-open\" data-message=\"Logging in first to save this listing.\"><i class=\"fal fa-heart\"><\/i><span>Sauvez<\/span><\/a>\r\n            <\/div>\r\n    \r\n            \r\n\r\n    <a href=\"https:\/\/globalcitieshub.org\/fr\/2026-heat-action-day-cities-beat-the-heat\/\" class=\"listing-thumb-link geodir-category-img-wrap fl-wrap\">\r\n        \r\n        <img width=\"424\" height=\"280\" class=\"respimg lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/04\/vignette_event_HAD-2.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/04\/vignette_event_HAD-2.png\" \/>\r\n            <\/a>\r\n        <div class=\"listing-avatar\"><a href=\"https:\/\/globalcitieshub.org\/fr\/author\/root_new\/\"><img alt='racine_nouveau' src='https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg' class='avatar avatar-80 photo' height='80' width='80' \/><\/a>\r\n        <span class=\"avatar-tooltip lpre-avatar\">Ajout\u00e9 par <strong>racine_nouveau<\/strong><\/span>\r\n    <\/div>\r\n    \r\n    \r\n     \r\n\r\n    \r\n    \r\n    \t<div class=\"geodir_status_date lstatus-opening\"><i class=\"fal fa-clock\"><\/i>02 juin 2026 14:00<\/div>\r\n\t\r\n    \r\n     \r\n      \r\n        <div class=\"lcfields-wrap dis-flex\"><\/div>\r\n    \r\n<\/div>\r\n<div class=\"azp_element preview_listing_content azp-element-azp-ggr3yufgsme geodir-category-content\" >\r\n\r\n    \r\n    <div class=\"geodir-category-content-title fl-wrap\">\r\n        <div class=\"geodir-category-content-title-item\">\r\n            <h3 class=\"title-sin_map\">\r\n                                <a href=\"https:\/\/globalcitieshub.org\/fr\/2026-heat-action-day-cities-beat-the-heat\/\">2026 Journ\u00e9e d'action contre la chaleur : Les villes combattent la chaleur<\/a>\r\n                            <\/h3>\r\n            <div class=\"geodir-category-location fl-wrap\"><a href=\"#\" class=\"map-item\" target=\"_blank\"><i class=\"fas fa-map-marker-alt\"><\/i>Villa Rigot &amp; en ligne<\/a><\/div>        <\/div>\r\n    <\/div>\r\n    <div class=\"geodir-category-text fl-wrap\">\r\n                        <div class=\"lcfields-wrap dis-flex\"><div class=\"azp_element lcustom_field lcfield-short_description ftitle-block-no azp-element-azp-3kx10ozfstc lcfield-wid-12 lcus-field-type-dflt lcus-sec-style-no authplan-hide-false\">\r\n    <div class=\"for-hide-on-author\"><\/div>\r\n                <div class=\"lcfield-inner\">\r\n                                                            <span class=\"lcfield-value\">Le 2 juin marque la 5e \u00e9dition de la Journ\u00e9e d'action contre la chaleur (HAD), une journ\u00e9e mondiale d'action et de sensibilisation \u00e0 la chaleur extr\u00eame. En 2026, le th\u00e8me de la Journ\u00e9e d'action contre la chaleur sera la chaleur \u00e0 l'int\u00e9rieur des b\u00e2timents. L'\u00e9v\u00e9nement marquera la Journ\u00e9e d'action contre la chaleur en mettant en lumi\u00e8re les meilleures pratiques et les initiatives modulables qui peuvent \u00eatre reproduites par les gouvernements locaux et r\u00e9gionaux dans le monde entier. Ensemble, nous pouvons #BeatTheHeat.<\/span>\r\n                                    <\/div>\r\n    <\/div>\r\n<\/div>\r\n            <\/div>\r\n        <div class=\"geodir-category-footer fl-wrap dis-flex\">\r\n                        <div class=\"geodir-opt-list dis-flex\">\r\n            <ul class=\"no-list-style\">\r\n                                                                                            <\/ul>\r\n        <\/div>\r\n            <\/div>\r\n    <\/div>\r\n    <\/article>\r\n<\/div>\r\n<!-- listing-item end-->                                  <\/div>\r\n                                                                <div class=\"view-all-listings\"><a href=\"https:\/\/www.genevacitieshub.org\/en\/events\/\"  class=\"btn  dec_btn  color2-bg\">D\u00e9couvrez toutes les annonces<i class=\"fal fa-arrow-alt-right\"><\/i><\/a><\/div>\r\n                            <\/div>\r\n                            <!-- end col-md-12 -->\r\n                        <\/div>\r\n                        <!-- end row -->\r\n                    <\/div>\r\n                    <!-- end container -->\r\n                <\/div>\r\n                <!-- list-main-wrap end-->\r\n\r\n        <\/div>\r\n        <!--  listings-grid-wrap end-->\r\n\r\n        \r\n                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80dccef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80dccef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7bfba5\" data-id=\"d7bfba5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec1629f elementor-widget elementor-widget-section_title\" data-id=\"ec1629f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"section-title section-title-dk-blue fl-wrap\">\r\n                        <h2><span>THEMES<\/span><\/h2>                                        <span class=\"section-separator section-separator-dk-blue\"><\/span> \r\n                         \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b80997f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b80997f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-976fbb2\" data-id=\"976fbb2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6789afb elementor-widget elementor-widget-text-editor\" data-id=\"6789afb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b><span lang=\"EN-US\">Le Global Cities Hub<\/span><\/b><span lang=\"EN-US\"> est en premi\u00e8re ligne pour \u00e9tablir et renforcer les liens entre les gouvernements locaux et r\u00e9gionaux d\u2019une part et les organisations internationales de l\u2019autre. Ces liens sont n\u00e9cessaires pour relever les grands d\u00e9fis auxquels sont confront\u00e9s les centres urbains du monde entier. Au travers de diverses initiatives, le GCH encourage la collaboration entre les villes, les maires et les r\u00e9seaux de villes pour promouvoir un multilat\u00e9ralisme plus inclusif au sein de l'\u00e9cosyst\u00e8me international genevois. Nous sommes engag\u00e9s dans les th\u00e8mes suivants : la protection de l'environnement et le changement climatique, le d\u00e9veloppement de villes intelligentes, la protection des droits humains et la promotion de la sant\u00e9 urbaine. En facilitant l'\u00e9change d\u2019exp\u00e9riences et l'action commune, nous visons \u00e0 cr\u00e9er des centres urbains durables, inclusifs et r\u00e9silients pour tous.<\/span><\/p><p><span lang=\"EN-US\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-001042b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"001042b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4c52195\" data-id=\"4c52195\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e64679 elementor-widget elementor-widget-image\" data-id=\"9e64679\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/globalcitieshub.org\/fr\/environment\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"350\" height=\"250\" class=\"elementor-animation-grow attachment-large size-large wp-image-20991 lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/website-topics-2.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/website-topics-2.png\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2e8c276\" data-id=\"2e8c276\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f7ca56 elementor-widget elementor-widget-image\" data-id=\"3f7ca56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/globalcitieshub.org\/fr\/smart-cities\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"350\" height=\"250\" class=\"elementor-animation-grow attachment-large size-large wp-image-20241 lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/2-2.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/2-2.png\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-efd8f46\" data-id=\"efd8f46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b64c19 elementor-widget elementor-widget-image\" data-id=\"0b64c19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/globalcitieshub.org\/fr\/urban-health\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"350\" height=\"250\" class=\"elementor-animation-grow attachment-large size-large wp-image-20363 lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/website-topics-1.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/website-topics-1.png\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-223be8e\" data-id=\"223be8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a02a4a elementor-widget elementor-widget-image\" data-id=\"7a02a4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/globalcitieshub.org\/fr\/human-rights\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"350\" height=\"250\" class=\"elementor-animation-grow attachment-large size-large wp-image-20242 lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/3-2.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/3-2.png\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-3092587\" data-id=\"3092587\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46a4da8 elementor-widget elementor-widget-image\" data-id=\"46a4da8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/globalcitieshub.org\/fr\/inclusive-multeralism\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"350\" height=\"250\" class=\"elementor-animation-grow attachment-large size-large wp-image-21026 lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/website-topics-1-1.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/08\/website-topics-1-1.png\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3620242 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3620242\" data-element_type=\"section\" data-e-type=\"section\" id=\"sec2\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05188aa\" data-id=\"05188aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8541bd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8541bd7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-050b2c5\" data-id=\"050b2c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6f2535 elementor-widget elementor-widget-section_title\" data-id=\"e6f2535\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"section-title section-title-dk-blue fl-wrap\">\r\n                        <h2><span>ACTUALITES<\/span><\/h2>                                        <span class=\"section-separator section-separator-dk-blue\"><\/span> \r\n                         \r\n        <\/div>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-419abbe elementor-widget elementor-widget-posts_grid\" data-id=\"419abbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"posts_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"cthiso-items cthiso-flex cthiso-big-pad cthiso-three-cols\">\r\n                        \r\n                                        <article id=\"post-27634\" class=\"cthiso-item post-article ptype-content post-27634 post type-post status-publish format-standard has-post-thumbnail hentry category-news tag-cities tag-hlpf tag-lrg tag-multilateralism tag-sdg11 tag-sdgs tag-sustainable-cities tag-sustainable-cities-and-communities tag-un\">\r\n                                                <div class=\"list-single-main-media fl-wrap\">\r\n                            <img loading=\"lazy\" width=\"381\" height=\"240\" class=\"respimg wp-post-image lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/04\/vignette_news_workshop-SDG11-381x240.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/04\/vignette_news_workshop-SDG11-381x240.png\" \/>                        <\/div>\r\n                                                <div class=\"list-single-main-item fl-wrap block_box post-content-wrap\">\r\n                            <h2 class=\"post-opt-title\"><a href=\"https:\/\/globalcitieshub.org\/fr\/preparing-the-review-of-sdg11-at-hlpf-2026\/\" rel=\"bookmark\">Pr\u00e9parer l'examen de l'ODD 11 au FPHN 2026<\/a><\/h2>Le Global Cities Hub a organis\u00e9 un atelier pour discuter du rapport de synth\u00e8se de l'ODD 11 avant le Forum politique de haut niveau (FPHN) de 2026. Ce rapport de synth\u00e8se est particuli\u00e8rement important car il s'agit de la derni\u00e8re r\u00e9vision de l'ODD 11 au HLPF. Lors de l'examen de l'ODD 11 au FPHN, les gouvernements locaux et r\u00e9gionaux seront pr\u00e9sents pour d\u00e9fendre le r\u00f4le des villes et des r\u00e9gions dans le multilat\u00e9ralisme.                            <span class=\"fw-separator\"><\/span>\r\n                            <div class=\"post-metas-wrap flex-items-center\">\r\n                                \r\n                            \r\n\r\n                                                                <div class=\"post-opt\">\r\n                                    <ul class=\"no-list-style flex-items-center\">\r\n                                        <li><i class=\"fal fa-calendar\"><\/i><span>13 mai 2026<\/span><\/li>                                                                                                                                                                        <li><i class=\"fal fa-tags\"><\/i><a href=\"https:\/\/globalcitieshub.org\/fr\/category\/news\/\" rel=\"category tag\">Actualit\u00e9s<\/a><\/li>  \r\n                                                                                                                        <\/ul>\r\n                                <\/div>\r\n                                                            <\/div>\r\n                                \r\n\r\n                \r\n                        <\/div>\r\n                    <\/article>\r\n\r\n                \r\n                                        <article id=\"post-27754\" class=\"cthiso-item post-article ptype-content post-27754 post type-post status-publish format-standard has-post-thumbnail hentry category-news tag-ai tag-cities tag-digitalization tag-digitlization tag-itu tag-lrg tag-multilateralism tag-technology tag-un tag-virtual-worlds\">\r\n                                                <div class=\"list-single-main-media fl-wrap\">\r\n                            <img loading=\"lazy\" width=\"381\" height=\"240\" class=\"respimg wp-post-image lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/05\/vignette_news_Citiverse-381x240.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/05\/vignette_news_Citiverse-381x240.png\" \/>                        <\/div>\r\n                                                <div class=\"list-single-main-item fl-wrap block_box post-content-wrap\">\r\n                            <h2 class=\"post-opt-title\"><a href=\"https:\/\/globalcitieshub.org\/fr\/ai-enabled-citiverse-global-policymaking-and-local-realities\/\" rel=\"bookmark\">La ville intelligente : \u00e9laboration de politiques mondiales et r\u00e9alit\u00e9s locales<\/a><\/h2>La troisi\u00e8me journ\u00e9e des Nations unies sur les mondes virtuels a permis de d\u00e9battre du concept de \"citiverse\", un paradigme num\u00e9rique int\u00e9grant l'intelligence artificielle (IA), les environnements virtuels immersifs et l'intelligence spatiale pour transformer la gouvernance urbaine et la prestation de services. Des maires et des responsables locaux ont apport\u00e9 leur contribution en pr\u00e9sentant des id\u00e9es pratiques tir\u00e9es d'exp\u00e9riences sur le terrain en mati\u00e8re de transformation urbaine.                            <span class=\"fw-separator\"><\/span>\r\n                            <div class=\"post-metas-wrap flex-items-center\">\r\n                                \r\n                            \r\n\r\n                                                                <div class=\"post-opt\">\r\n                                    <ul class=\"no-list-style flex-items-center\">\r\n                                        <li><i class=\"fal fa-calendar\"><\/i><span>11 mai 2026<\/span><\/li>                                                                                                                                                                        <li><i class=\"fal fa-tags\"><\/i><a href=\"https:\/\/globalcitieshub.org\/fr\/category\/news\/\" rel=\"category tag\">Actualit\u00e9s<\/a><\/li>  \r\n                                                                                                                        <\/ul>\r\n                                <\/div>\r\n                                                            <\/div>\r\n                                \r\n\r\n                \r\n                        <\/div>\r\n                    <\/article>\r\n\r\n                \r\n                                        <article id=\"post-27728\" class=\"cthiso-item post-article ptype-content post-27728 post type-post status-publish format-standard has-post-thumbnail hentry category-news tag-cities tag-international-law tag-multilateralism\">\r\n                                                <div class=\"list-single-main-media fl-wrap\">\r\n                            <img loading=\"lazy\" width=\"381\" height=\"240\" class=\"respimg wp-post-image lazy\" alt=\"\" data-src=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/05\/vignette_news_internl-law-1-381x240.png\" data-lazy=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2026\/05\/vignette_news_internl-law-1-381x240.png\" \/>                        <\/div>\r\n                                                <div class=\"list-single-main-item fl-wrap block_box post-content-wrap\">\r\n                            <h2 class=\"post-opt-title\"><a href=\"https:\/\/globalcitieshub.org\/fr\/alternative-lawmaking-for-a-new-multilateralism-cities-as-co-creators\/\" rel=\"bookmark\">L\u00e9gislation alternative pour un nouveau multilat\u00e9ralisme : les villes en tant que co-cr\u00e9atrices ?<\/a><\/h2>La table ronde intitul\u00e9e \u201cAlternative lawmaking for a new multilateralism : cities as co-creators ?\u201d a explor\u00e9 la mani\u00e8re dont les GRL pourraient contribuer plus directement \u00e0 la cr\u00e9ation de normes internationales. Elle s'est concentr\u00e9e sur la question de savoir si l'\u00e9volution des formes de gouvernance internationale pouvait ouvrir un espace pour les villes, qui ne seraient pas simplement des co-cr\u00e9ateurs actifs de normes internationales.                            <span class=\"fw-separator\"><\/span>\r\n                            <div class=\"post-metas-wrap flex-items-center\">\r\n                                \r\n                            \r\n\r\n                                                                <div class=\"post-opt\">\r\n                                    <ul class=\"no-list-style flex-items-center\">\r\n                                        <li><i class=\"fal fa-calendar\"><\/i><span>05 mai 2026<\/span><\/li>                                                                                                                                                                        <li><i class=\"fal fa-tags\"><\/i><a href=\"https:\/\/globalcitieshub.org\/fr\/category\/news\/\" rel=\"category tag\">Actualit\u00e9s<\/a><\/li>  \r\n                                                                                                                        <\/ul>\r\n                                <\/div>\r\n                                                            <\/div>\r\n                                \r\n\r\n                \r\n                        <\/div>\r\n                    <\/article>\r\n\r\n                \r\n\r\n                \r\n\r\n             \r\n\r\n        <\/div>\r\n                <div class=\"view-all-listings\"><a href=\"#\"  class=\"btn  dec_btn  color2-bg\">Lire tous les messages<i class=\"fal fa-arrow-alt-right\"><\/i><\/a><\/div>                \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Global Cities Hub Connecter les gouvernements locaux et r\u00e9gionaux aux Nations Unies et \u00e0 d'autres organisations internationales FAITS MARQUANTS Sauvegarder Ajout\u00e9 par la racine 11 d\u00e9cembre 2024 14:00 pm Renforcer le dialogue local-global pour une gestion durable des d\u00e9chets dans les zones urbaines En ligne L'urbanisation rapide de la population mondiale, avec plus de 4,4 milliards de personnes r\u00e9sidant actuellement dans les villes, a ... <\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"home-fullscreen.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-545","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Global Cities Hub<\/title>\n<meta name=\"description\" content=\"Global Cities Hub supports cities and city networks to contribute more effectively to multilateral processes and bodies in Geneva.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"Global Cities Hub supports cities and city networks to contribute more effectively to multilateral processes and bodies in Geneva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-13T10:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/11\/water-waste-2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"name\":\"Home - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/water-waste-2.png\",\"datePublished\":\"2016-10-14T09:44:04+00:00\",\"dateModified\":\"2024-11-13T10:00:19+00:00\",\"description\":\"Global Cities Hub supports cities and city networks to contribute more effectively to multilateral processes and bodies in Geneva.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/water-waste-2.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/water-waste-2.png\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accueil - Global Cities Hub","description":"Global Cities Hub aide les villes et les r\u00e9seaux de villes \u00e0 contribuer plus efficacement aux processus et organes multilat\u00e9raux \u00e0 Gen\u00e8ve.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Home - Global Cities Hub","og_description":"Global Cities Hub supports cities and city networks to contribute more effectively to multilateral processes and bodies in Geneva.","og_url":"https:\/\/globalcitieshub.org\/fr\/","og_site_name":"Global Cities Hub","article_modified_time":"2024-11-13T10:00:19+00:00","og_image":[{"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/11\/water-waste-2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@genevacitieshub","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/fr\/","url":"https:\/\/globalcitieshub.org\/fr\/","name":"Accueil - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/fr\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/11\/water-waste-2.png","datePublished":"2016-10-14T09:44:04+00:00","dateModified":"2024-11-13T10:00:19+00:00","description":"Global Cities Hub aide les villes et les r\u00e9seaux de villes \u00e0 contribuer plus efficacement aux processus et organes multilat\u00e9raux \u00e0 Gen\u00e8ve.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/11\/water-waste-2.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2024\/11\/water-waste-2.png"},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/fr\/#website","url":"https:\/\/globalcitieshub.org\/fr\/","name":"Global Cities Hub","description":"Relier les gouvernements locaux et r\u00e9gionaux aux Nations unies et \u00e0 d'autres organisations internationales","publisher":{"@id":"https:\/\/globalcitieshub.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/fr\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/pages\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":429,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/pages\/545\/revisions"}],"predecessor-version":[{"id":24037,"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/pages\/545\/revisions\/24037"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/fr\/wp-json\/wp\/v2\/media?parent=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}