{"id":25451,"date":"2025-10-09T14:37:23","date_gmt":"2025-10-09T12:37:23","guid":{"rendered":"https:\/\/globalcitieshub.org\/?p=25451"},"modified":"2025-10-27T14:49:48","modified_gmt":"2025-10-27T13:49:48","slug":"mayors-advocate-for-a-stronger-forum-within-the-un-system","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/","title":{"rendered":"Los alcaldes abogan por un foro m\u00e1s fuerte dentro del sistema de la ONU"},"content":{"rendered":"<p>El 5\u00ba Foro de Alcaldes de las Naciones Unidas (FoM): \"Las ciudades construyen el futuro\" se celebr\u00f3 los d\u00edas 6 y 7 de octubre de 2025 en el Palacio de las Naciones de Ginebra y reuni\u00f3 a representantes de 80 ciudades, entre ellos 50 alcaldes y tenientes de alcalde de todas las regiones del mundo. Este a\u00f1o, la FoM se aline\u00f3 con el <a href=\"https:\/\/hlpf.un.org\/home\">Foro Pol\u00edtico de Alto Nivel de las Naciones Unidas sobre el Desarrollo Sostenible<\/a> (que se celebra anualmente en julio en Nueva York) y abord\u00f3 los mismos temas prioritarios: buena salud y bienestar (ODS 3), igualdad de g\u00e9nero (ODS 5) y trabajo digno y crecimiento econ\u00f3mico (ODS 8). Tambi\u00e9n se centr\u00f3 en los mecanismos de financiaci\u00f3n clim\u00e1tica, las Revisiones Locales Voluntarias (RLV) y los retos de la vivienda.<\/p>\n\n\n\n<p>En su discurso de apertura, Christina Kitsos, Vicealcaldesa de Ginebra y Presidenta del Global Cities Hub (GCH), reafirm\u00f3 su compromiso con el multilateralismo, subrayando que <em>\"el Foro de Alcaldes conecta las ambiciones mundiales con las realidades locales y pone de relieve el valor a\u00f1adido del multilateralismo integrador. Nos recuerda que las ciudades y las regiones son actores clave en la aplicaci\u00f3n de las decisiones globales\"<\/em> Invit\u00f3 a los Estados a reforzar su compromiso y a renovar el mandato del Foro cuando llegue el momento, subrayando la necesidad de \"<em>un espacio donde Estados, ciudades y regiones puedan reunirse, dialogar y cocrear las soluciones del ma\u00f1ana<\/em>.\"<\/p>\n\n\n\n<p>Su mensaje reson\u00f3 con el de otros oradores de alto nivel (el ex Presidente de Suiza, el l\u00edder de la ciudad de Glasgow, representantes de la CEPE, la OIT, el Congreso de Poderes Locales y Regionales del Consejo de Europa y CGLU), que destacaron la importancia de la gobernanza multinivel y el papel fundamental de las ciudades en la consecuci\u00f3n de la sostenibilidad, la resiliencia y los Objetivos de Desarrollo Sostenible.<\/p>\n\n\n\n<p>Durante dos d\u00edas, alcaldes, Estados, organizaciones internacionales, ONG, el mundo acad\u00e9mico y el sector privado participaron en seis sesiones tem\u00e1ticas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Buena salud y bienestar (ODS 3):<\/strong> Los alcaldes intercambiaron experiencias sobre la mejora de la salud p\u00fablica a trav\u00e9s del transporte, los espacios verdes, la calidad del aire y la vivienda. <a href=\"https:\/\/www.who.int\/health-topics\/urban-health#tab=tab_1\">OMS<\/a> destacaron la planificaci\u00f3n urbana como medida fundamental de salud p\u00fablica. Varios alcaldes pidieron la devoluci\u00f3n de competencias y autoridad legal para permitir una acci\u00f3n local eficaz. Por ejemplo, Nu\u00f1oa (Chile) cit\u00f3 las dificultades para contratar personal sanitario debido a las normas centralizadas, mientras que Lyon (Francia) inform\u00f3 de una reducci\u00f3n de 40% de la contaminaci\u00f3n atmosf\u00e9rica en seis a\u00f1os gracias a la ampliaci\u00f3n de los carriles bici, las zonas peatonales y los l\u00edmites de velocidad.<\/li>\n\n\n\n<li><strong>Igualdad de g\u00e9nero (ODS 5):<\/strong> Las ciudades presentaron iniciativas para fomentar la igualdad, combatir la violencia de g\u00e9nero y potenciar la participaci\u00f3n de la mujer en la pol\u00edtica. <a href=\"https:\/\/www.unwomen.org\/en\">ONU Mujeres<\/a> destacaron que las pol\u00edticas, iniciativas y asignaciones presupuestarias espec\u00edficas son esenciales para la seguridad y la capacitaci\u00f3n de las mujeres, su contribuci\u00f3n a la vida pol\u00edtica y econ\u00f3mica, as\u00ed como la representaci\u00f3n equitativa en la gobernanza y la mano de obra. Mannheim (Alemania) present\u00f3 programas de apoyo a la iniciativa empresarial femenina y a las empresas dirigidas por mujeres, mientras que Nairobi (Kenia) destac\u00f3 su norma de dos tercios de g\u00e9nero para los nombramientos municipales, as\u00ed como las iniciativas que promueven el acceso de las mujeres al deporte. Tras una impactante <em>\"Mujer y Alcalde\"<\/em> las alcaldesas adoptaron un <a href=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/10\/Women-Mayors-Declaration.pdf\"><strong>Declaraci\u00f3n<\/strong><\/a> reafirmando el papel clave de las mujeres en la configuraci\u00f3n de ciudades resilientes, inclusivas y sostenibles, y pidiendo medidas urgentes para garantizar la capacitaci\u00f3n, la seguridad y la representaci\u00f3n equitativa de las mujeres en la toma de decisiones.<\/li>\n\n\n\n<li><strong>Trabajo decente y crecimiento econ\u00f3mico (ODS 8):<\/strong> <a href=\"https:\/\/www.ilo.org\/\">OIT<\/a> y las ciudades participantes destacaron las econom\u00edas locales como motores de innovaci\u00f3n, empleo y prosperidad integradora. La innovaci\u00f3n y la transformaci\u00f3n digital surgieron como motores clave del crecimiento. Varios alcaldes subrayaron la importancia de integrar a los grupos vulnerables en la poblaci\u00f3n activa. \u00d8ygarden (Noruega) ilustr\u00f3 c\u00f3mo la integraci\u00f3n de los refugiados en funciones de apoyo sanitario les ayuda a incorporarse a la poblaci\u00f3n activa y alivia la presi\u00f3n sobre el personal m\u00e9dico. San Mateo Atenco (M\u00e9xico) present\u00f3 su modernizaci\u00f3n de la industria zapatera local para garantizar un trabajo digno y preservar la identidad cultural.<\/li>\n\n\n\n<li><strong>Mecanismos de financiaci\u00f3n de la lucha contra el cambio clim\u00e1tico<\/strong>: Los participantes pidieron un\u00e1nimemente que se destinen m\u00e1s fondos directamente a las ciudades, que est\u00e1n a la vanguardia de la acci\u00f3n por el clima. Destacaron la importancia de las asociaciones internacionales, la colaboraci\u00f3n p\u00fablico-privada y unos marcos jur\u00eddicos y financieros claros para las inversiones clim\u00e1ticas a largo plazo que tambi\u00e9n generen empleo. Tallin (Estonia) describi\u00f3 los retos que plantea la renovaci\u00f3n de sus edificios, que requiere una financiaci\u00f3n m\u00e1s previsible y a m\u00e1s largo plazo para ampliar los proyectos, mientras que Amm\u00e1n (Jordania) abog\u00f3 por una financiaci\u00f3n flexible para proteger a las personas y las infraestructuras de las cat\u00e1strofes relacionadas con el clima gracias a un sistema eficaz de alerta temprana.<\/li>\n\n\n\n<li><strong>Retos en materia de vivienda<\/strong>: <a href=\"https:\/\/unhabitat.org\/topic\/housing\">ONU-H\u00e1bitat<\/a> hizo hincapi\u00e9 en el derecho a una vivienda adecuada como piedra angular de otros ODS, como la salud, la educaci\u00f3n, la igualdad de g\u00e9nero y el crecimiento econ\u00f3mico. Con una crisis mundial de la vivienda que afecta a todas las regiones, el papel de los GLR es m\u00e1s crucial que nunca en la elaboraci\u00f3n de pol\u00edticas de vivienda eficaces. Aunque a menudo carecen de las herramientas legales, financieras e institucionales para responder adecuadamente, muchos de ellos est\u00e1n aplicando soluciones creativas -desde modelos de vivienda social y cooperativa hasta desarrollos dirigidos por la comunidad y asociaciones p\u00fablico-privadas- para ampliar la vivienda asequible, renovar edificios antiguos o inseguros e integrar la sostenibilidad y la resiliencia en la planificaci\u00f3n urbana. Bruselas (B\u00e9lgica) promueve incentivos de rehabilitaci\u00f3n para la vivienda social, mientras que San Miguelito (Panam\u00e1), una de las ciudades m\u00e1s densamente pobladas de Panam\u00e1, ha desarrollado su primer plan urbano para garantizar la seguridad de la tenencia, promover la vivienda social y facilitar el acceso de los j\u00f3venes al cr\u00e9dito para la vivienda.<\/li>\n\n\n\n<li><a href=\"https:\/\/sdgs.un.org\/topics\/voluntary-local-reviews\"><strong>Revisiones locales voluntarias<\/strong><\/a><strong> (VLR):<\/strong> Los debates pusieron de relieve la importancia pol\u00edtica de los RLV como instrumentos que van m\u00e1s all\u00e1 de la presentaci\u00f3n de informes. Los alcaldes subrayaron que los RLV sirven como compromisos concretos, ofreciendo un medio para mostrar las innovaciones locales, atraer financiaci\u00f3n y fomentar la transparencia con sus electores. A pesar de los limitados recursos humanos y financieros, la fragmentaci\u00f3n de los datos y la insuficiencia de orientaciones pr\u00e1cticas, Lusaka (Zambia) y Bursa (Turqu\u00eda) completaron sus primeras RLV, alineando las estrategias municipales con los ODS y reforzando la confianza de la comunidad. A medida que las ciudades asumen un papel m\u00e1s destacado en los asuntos internacionales, las evaluaciones locales voluntarias (RLV) ofrecen un medio tangible para que contribuyan y participen en la gobernanza mundial. Al hacerlo, las RLV promueven una forma m\u00e1s inclusiva de multilateralismo, en la que las ciudades colaboran con los Estados y otras partes interesadas. Adem\u00e1s, a trav\u00e9s de las RLV, las ciudades se posicionan como aliados estrat\u00e9gicos en la configuraci\u00f3n de la agenda para despu\u00e9s de 2030.<\/li>\n<\/ul>\n\n\n\n<p>Otros acontecimientos:<\/p>\n\n\n\n<p>Al margen del Foro, el GCH coorganiz\u00f3 cuatro actos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/globalcitieshub.org\/es\/building-resilient-cities-in-a-warming-world-cooling-becomes-core-infrastructure\/\"><strong>Refrigeraci\u00f3n y construcci\u00f3n para la resiliencia urbana<\/strong><\/a><em>: Soluciones locales, impacto global<\/em> estudi\u00f3 estrategias de refrigeraci\u00f3n urbana y dise\u00f1o de edificios en un contexto de aumento de las temperaturas.<\/li>\n\n\n\n<li>A <a href=\"https:\/\/globalcitieshub.org\/es\/this-is-a-table-of-partners-mayors-dialogue-with-international-organizations\/\"><strong>Reuni\u00f3n de alto nivel entre alcaldes y jefes de organizaciones internacionales<\/strong><\/a> (ONU-H\u00e1bitat, UIT, UNDRR, CEPE) permitieron intercambios directos sobre vivienda, resiliencia urbana, digitalizaci\u00f3n y ciudades inteligentes.<\/li>\n\n\n\n<li><a href=\"https:\/\/globalcitieshub.org\/es\/cities-in-the-lead-action-oriented-plans-for-vlrs\/\"><strong>VLRs - Elaborar el proceso: Las ciudades hablan entre s\u00ed<\/strong><\/a> examin\u00f3 las opciones estrat\u00e9gicas y pol\u00edticas a la hora de llevar a cabo las RLV.<\/li>\n\n\n\n<li>El <a href=\"https:\/\/globalcitieshub.org\/es\/mayors-and-business-leaders-shape-the-cities-of-tomorrow\/\"><strong>Di\u00e1logo sobre el Futuro Urbano<\/strong><\/a>organizada por la <a href=\"https:\/\/www.weforum.org\/\">Foro Econ\u00f3mico Mundial<\/a>reuni\u00f3 a alcaldes, l\u00edderes empresariales y de la sociedad civil para explorar c\u00f3mo las ciudades y el sector privado pueden trabajar codo con codo para acelerar la innovaci\u00f3n y el desarrollo urbano sostenible.<\/li>\n<\/ul>\n\n\n\n<p>Resultado:<\/p>\n\n\n\n<p>El Foro concluy\u00f3 con la adopci\u00f3n de recomendaciones a los Estados, a trav\u00e9s del Comit\u00e9 de Desarrollo Urbano, Vivienda y Ordenaci\u00f3n del Territorio de la CEPE. Estas recomendaciones fueron negociadas por las ciudades participantes e incluyen un lenguaje clave sobre todos los temas debatidos y sobre el desarrollo del propio FoM. Los alcaldes reafirmaron que el Foro sirve como un \u00f3rgano eficaz de la ONU para que las ciudades participen en el trabajo de la ONU y para avanzar efectivamente en la localizaci\u00f3n de los ODS, incluyendo el fomento de un compromiso m\u00e1s sustancial entre los alcaldes y los Estados en la aplicaci\u00f3n de los ODS. Tambi\u00e9n subrayaron que el FoM debe utilizarse como plataforma para debatir cualquier marco internacional que suceda a la Agenda 2030 y que debe reforzarse y ampliarse dentro del sistema de las Naciones Unidas. La nueva Mesa del FoM, compuesta por los alcaldes de Heidelberg (Presidencia), Bristol y Hradec Kr\u00e1lov\u00e9, tendr\u00e1 que presentar recomendaciones a este respecto antes del pr\u00f3ximo Foro de Alcaldes de la ONU, que se celebrar\u00e1 en 2026.<\/p>\n\n\n\n<p>Conclusi\u00f3n:<\/p>\n\n\n\n<p>El 5\u00ba FoM fue un \u00e9xito rotundo, demostrando la creciente influencia de las ciudades como socios esenciales en la gobernanza mundial. Con alcaldes de todas las regiones compartiendo experiencias pr\u00e1cticas y soluciones innovadoras, el Foro demostr\u00f3 una vez m\u00e1s su valor \u00fanico para vincular la acci\u00f3n local a los objetivos mundiales. El GCH, orgulloso socio desde la primera edici\u00f3n del FoM en 2020, mantiene su compromiso de profundizar en la colaboraci\u00f3n con la CEPE y todas las dem\u00e1s Comisiones Econ\u00f3micas Regionales de la ONU para globalizar y fortalecer el FoM dentro del sistema de la ONU. El GCH hace un llamamiento a los Estados para que sigan apoyando esta plataforma vital que encarna el multilateralismo inclusivo previsto por el Secretario General de las Naciones Unidas, Guterres, en un momento en que la ONU trata de reimaginarse a s\u00ed misma.<\/p>\n\n\n\n<p><strong>La 6\u00aa edici\u00f3n del Foro de Alcaldes de las Naciones Unidas se celebrar\u00e1 los d\u00edas 12 y 13 de octubre de 2026 en Ginebra. \u00a1El Global Cities Hub lo espera con impaciencia!<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>El V Foro de Alcaldes de las Naciones Unidas (FoM), celebrado los d\u00edas 6 y 7 de octubre de 2025 en Ginebra, reuni\u00f3 a representantes de 80 ciudades de todas las regiones. Centrado en el tema \"Las ciudades construyen el futuro\", el Foro se aline\u00f3 con el Foro Pol\u00edtico de Alto Nivel de las Naciones Unidas sobre el Desarrollo Sostenible 2025 y abord\u00f3 cuestiones mundiales clave como la salud y el bienestar (ODS 3), la igualdad de g\u00e9nero (ODS 5), el trabajo decente (ODS 8), la financiaci\u00f3n de la lucha contra el cambio clim\u00e1tico y la vivienda. Los participantes hicieron un llamamiento un\u00e1nime para reforzar y ampliar la Plataforma de Acci\u00f3n dentro del sistema de las Naciones Unidas, reconoci\u00e9ndola como una plataforma vital que tiende puentes entre la acci\u00f3n local y la formulaci\u00f3n de pol\u00edticas mundiales.<\/p>","protected":false},"author":1,"featured_media":25148,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[199,515,348,215,197,196,334,201,203,347,346],"class_list":["post-25451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cities","tag-cities-shaping-the-future","tag-fom","tag-forum-of-mayors","tag-lrg","tag-multilateralism","tag-regions","tag-sdgs","tag-un","tag-un-fom","tag-un-forum-of-mayors"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mayors Advocate for a Stronger Forum within the UN System - Global Cities Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mayors Advocate for a Stronger Forum within the UN System - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"The 5th UN Forum of Mayors (FoM), held on 6\u20137 October 2025 in Geneva, brought together representatives from 80 cities from all regions. Centred on the theme \u201cCities shaping the future,\u201d the Forum aligned with the 2025 UN High-Level Political Forum on Sustainable Development and tackled key global issues such as health and well-being (SDG 3), gender equality (SDG 5), decent work (SDG 8), climate finance, and housing. Participants unanimously called for reinforcing and expanding the FoM within the UN system, recognizing it as a vital platform that bridges local action and global policy-making.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-09T12:37:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T13:49:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/10\/vignette_news_FoMgeneral.png\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"root_new\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"root_new\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/\"},\"author\":{\"name\":\"root_new\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"Mayors Advocate for a Stronger Forum within the UN System\",\"datePublished\":\"2025-10-09T12:37:23+00:00\",\"dateModified\":\"2025-10-27T13:49:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/\"},\"wordCount\":1315,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/vignette_news_FoMgeneral.png\",\"keywords\":[\"cities\",\"Cities Shaping the Future\",\"FoM\",\"forum of mayors\",\"LRG\",\"multilateralism\",\"regions\",\"SDGs\",\"UN\",\"UN FoM\",\"UN Forum of Mayors\"],\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/\",\"name\":\"Mayors Advocate for a Stronger Forum within the UN System - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/vignette_news_FoMgeneral.png\",\"datePublished\":\"2025-10-09T12:37:23+00:00\",\"dateModified\":\"2025-10-27T13:49:48+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/mayors-advocate-for-a-stronger-forum-within-the-un-system\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/vignette_news_FoMgeneral.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/vignette_news_FoMgeneral.png\",\"width\":786,\"height\":524},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"root_new\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"caption\":\"root_new\"},\"sameAs\":[\"http:\\\/\\\/gch.dev-bulbera.com\"],\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los alcaldes abogan por un foro m\u00e1s fuerte dentro del sistema de la ONU - Global Cities Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/","og_locale":"es_ES","og_type":"article","og_title":"Mayors Advocate for a Stronger Forum within the UN System - Global Cities Hub","og_description":"The 5th UN Forum of Mayors (FoM), held on 6\u20137 October 2025 in Geneva, brought together representatives from 80 cities from all regions. Centred on the theme \u201cCities shaping the future,\u201d the Forum aligned with the 2025 UN High-Level Political Forum on Sustainable Development and tackled key global issues such as health and well-being (SDG 3), gender equality (SDG 5), decent work (SDG 8), climate finance, and housing. Participants unanimously called for reinforcing and expanding the FoM within the UN system, recognizing it as a vital platform that bridges local action and global policy-making.","og_url":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/","og_site_name":"Global Cities Hub","article_published_time":"2025-10-09T12:37:23+00:00","article_modified_time":"2025-10-27T13:49:48+00:00","og_image":[{"width":786,"height":524,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/10\/vignette_news_FoMgeneral.png","type":"image\/png"}],"author":"root_new","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"Escrito por":"root_new","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/"},"author":{"name":"root_new","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"Mayors Advocate for a Stronger Forum within the UN System","datePublished":"2025-10-09T12:37:23+00:00","dateModified":"2025-10-27T13:49:48+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/"},"wordCount":1315,"publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/10\/vignette_news_FoMgeneral.png","keywords":["cities","Cities Shaping the Future","FoM","forum of mayors","LRG","multilateralism","regions","SDGs","UN","UN FoM","UN Forum of Mayors"],"articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/","url":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/","name":"Los alcaldes abogan por un foro m\u00e1s fuerte dentro del sistema de la ONU - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/10\/vignette_news_FoMgeneral.png","datePublished":"2025-10-09T12:37:23+00:00","dateModified":"2025-10-27T13:49:48+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/mayors-advocate-for-a-stronger-forum-within-the-un-system\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/10\/vignette_news_FoMgeneral.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/10\/vignette_news_FoMgeneral.png","width":786,"height":524},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/es\/#website","url":"https:\/\/globalcitieshub.org\/es\/","name":"Global Cities Hub","description":"Conectar a los gobiernos locales y regionales con las Naciones Unidas y otras organizaciones internacionales.","publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/es\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"raiz_nueva","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","url":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","caption":"root_new"},"sameAs":["http:\/\/gch.dev-bulbera.com"],"url":"https:\/\/globalcitieshub.org\/es\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/25451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/comments?post=25451"}],"version-history":[{"count":1,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/25451\/revisions"}],"predecessor-version":[{"id":25452,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/25451\/revisions\/25452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media\/25148"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media?parent=25451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/categories?post=25451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/tags?post=25451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}