{"id":23657,"date":"2025-03-19T11:46:00","date_gmt":"2025-03-19T10:46:00","guid":{"rendered":"https:\/\/globalcitieshub.org\/?p=23657"},"modified":"2025-03-24T11:46:27","modified_gmt":"2025-03-24T10:46:27","slug":"localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/","title":{"rendered":"Localizaci\u00f3n del multilateralismo: el papel de los gobiernos locales y regionales en la promoci\u00f3n de los derechos humanos y los ODS"},"content":{"rendered":"<p>En una sala repleta de representantes de m\u00e1s de 30 Estados miembros y organizaciones internacionales, el Global Cities Hub (GCH), en colaboraci\u00f3n con la Universidad de Bolonia y la Plataforma de Derechos Humanos de Ginebra, dirigi\u00f3 un interesante debate sobre el papel de los gobiernos locales y regionales en la aplicaci\u00f3n de los derechos humanos. El acto, organizado como evento paralelo al Consejo de Derechos Humanos de las Naciones Unidas (CDH), se bas\u00f3 en la labor iniciada hace un a\u00f1o con varias resoluciones y declaraciones conjuntas del CDH y tras el <a href=\"https:\/\/globalcitieshub.org\/es\/bridging-human-rights-and-sdgs-systems-data-collection-bringing-local-and-regional-governments-into-the-equation\/\">Mesa redonda de expertos de Bolonia sobre planificaci\u00f3n y recopilaci\u00f3n de datos por los NMIRF<\/a>. El resultado fue la publicaci\u00f3n de \"<a href=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/02\/Briefing-25_localizing_multilateralism.pdf\">Localizaci\u00f3n del multilateralismo: el papel de los GLR en la promoci\u00f3n de los derechos humanos y los ODS<\/a>\u201c.<\/p>\n\n\n\n<p>El debate puso de relieve el papel esencial que desempe\u00f1an los GLR en la promoci\u00f3n y aplicaci\u00f3n de los derechos humanos a escala subnacional, garantizando que los compromisos internacionales se traduzcan en acciones tangibles para sus residentes. Los oradores subrayaron la necesidad de que el sistema internacional de derechos humanos se comprometa m\u00e1s eficazmente con los GLR para dotarlos de las herramientas, los conocimientos y los recursos necesarios para cumplir sus obligaciones en materia de derechos humanos.<\/p>\n\n\n\n<p><strong>Colmar la brecha entre las normas mundiales y las realidades locales<\/strong><\/p>\n\n\n\n<p>Los GLR est\u00e1n en primera l\u00ednea de la prestaci\u00f3n de servicios p\u00fablicos esenciales y la protecci\u00f3n de los derechos humanos. Ya se trate de garantizar el acceso a la vivienda, mejorar las infraestructuras locales o facilitar la libertad de reuni\u00f3n, los municipios son el primer punto de contacto para los residentes que desean ejercer sus derechos. Sin embargo, a pesar de su papel fundamental en este contexto, muchos gobiernos locales carecen de la formaci\u00f3n y los recursos financieros necesarios para cumplir con las obligaciones internacionales en materia de derechos humanos.<\/p>\n\n\n\n<p>El acto puso de relieve que los mecanismos internacionales de derechos humanos siguen pasando por alto en gran medida el papel de los GLR. Existe, por ejemplo, una necesidad acuciante de incorporar <a href=\"https:\/\/globalcitieshub.org\/es\/the-coalition-for-local-and-regional-governments-in-upr-publishes-upr-tips-for-lrgs\/\">Los GLR en el Examen Peri\u00f3dico Universal (EPU)<\/a>. Para ello, se puede recurrir a las herramientas creadas en el marco de los ODS para que los GLR informen sobre sus progresos (ex\u00e1menes voluntarios locales o subnacionales) a fin de evaluar los derechos humanos a nivel local.<\/p>\n\n\n\n<p>La publicaci\u00f3n \"<a href=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/02\/Briefing-25_localizing_multilateralism.pdf\">Localizaci\u00f3n del multilateralismo: el papel de los GLR en la promoci\u00f3n de los derechos humanos y los ODS<\/a>\u201c<em>,<\/em> presentado oficialmente durante el acto paralelo, ofrece recomendaciones concretas sobre c\u00f3mo reforzar este compromiso, en particular fomentando la recopilaci\u00f3n y el uso de datos desglosados para evaluar los avances en materia de derechos humanos a escala local. Arroja luz sobre una importante laguna en la gobernanza internacional de los derechos humanos: la ausencia de un compromiso sistem\u00e1tico con los GLR en las revisiones de los \u00f3rganos de tratados, las sesiones del Consejo de Derechos Humanos y los mecanismos de presentaci\u00f3n de informes de la ONU.<\/p>\n\n\n\n<p>\"Esto es s\u00f3lo el principio\", afirm\u00f3 uno de los coautores. \"Casi no hay investigaciones serias, ni consideraciones significativas, ni datos estructurados en la llamada maquinaria internacional de derechos humanos sobre el papel de los GLR. Esto debe cambiar. Los Estados y el sistema de la ONU deben empezar a integrar a los gobiernos locales en los debates, las pol\u00edticas y los mecanismos de rendici\u00f3n de cuentas sobre derechos humanos.\"<\/p>\n\n\n\n<p><strong>Llamamiento a la acci\u00f3n: Reconocer a los GLR como agentes de derechos humanos<\/strong><\/p>\n\n\n\n<p>\"Los derechos humanos -nuestros derechos- empiezan en el \u00e1mbito local\", subray\u00f3 la codirectora del GCH, Kamelia Kemileva. \"De poco sirven las negociaciones abstractas, interestatales o los compromisos globales si no llegan a los municipios responsables de convertirlos en realidad\".<\/p>\n\n\n\n<p>El acto concluy\u00f3 con un mensaje contundente: para que los derechos humanos se apliquen de verdad, deben localizarse, y eso empieza por reconocer y capacitar a los municipios, ciudades y regiones que aplican los compromisos en materia de derechos humanos para sus residentes y comunidades.<\/p>","protected":false},"excerpt":{"rendered":"<p>En una sala repleta de representantes de m\u00e1s de 30 Estados miembros y organizaciones internacionales, el Global Cities Hub (GCH), en colaboraci\u00f3n con la Universidad de Bolonia y la Plataforma de Derechos Humanos de Ginebra, dirigi\u00f3 un interesante debate sobre el papel de los gobiernos locales y regionales (GLR) en la aplicaci\u00f3n de los derechos humanos. El acto, organizado como ... <\/p>","protected":false},"author":1,"featured_media":23554,"comment_status":"closed","ping_status":"0","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[199,222,328,329,196,201],"class_list":["post-23657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cities","tag-human-rights","tag-localization","tag-localizing","tag-multilateralism","tag-sdgs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Localizing multilateralism: the role of local and regional governments in advancing human rights and SDGs - Global Cities Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Localizing multilateralism: the role of local and regional governments in advancing human rights and SDGs - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"In a room packed with representatives from more than 30 member states and international organizations, the Global Cities Hub (GCH), in collaboration with the University of Bologna and the Geneva Human Rights Platform, led an engaging discussion on the role of Local and Regional Governments (LRGs) in human rights implementation. The event, organized as a &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-19T10:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T10:46:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/03\/vignette-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"root_new\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"root_new\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/\"},\"author\":{\"name\":\"root_new\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"Localizing multilateralism: the role of local and regional governments in advancing human rights and SDGs\",\"datePublished\":\"2025-03-19T10:46:00+00:00\",\"dateModified\":\"2025-03-24T10:46:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/\"},\"wordCount\":557,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/vignette-2.png\",\"keywords\":[\"cities\",\"human rights\",\"localization\",\"localizing\",\"multilateralism\",\"SDGs\"],\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/\",\"name\":\"Localizing multilateralism: the role of local and regional governments in advancing human rights and SDGs - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/vignette-2.png\",\"datePublished\":\"2025-03-19T10:46:00+00:00\",\"dateModified\":\"2025-03-24T10:46:27+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/vignette-2.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/vignette-2.png\",\"width\":786,\"height\":524},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"root_new\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/plugins\\\/townhub-add-ons\\\/assets\\\/images\\\/avatar.jpg\",\"caption\":\"root_new\"},\"sameAs\":[\"http:\\\/\\\/gch.dev-bulbera.com\"],\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Localizaci\u00f3n del multilateralismo: el papel de los gobiernos locales y regionales en la promoci\u00f3n de los derechos humanos y los ODS - Global Cities Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/","og_locale":"es_ES","og_type":"article","og_title":"Localizing multilateralism: the role of local and regional governments in advancing human rights and SDGs - Global Cities Hub","og_description":"In a room packed with representatives from more than 30 member states and international organizations, the Global Cities Hub (GCH), in collaboration with the University of Bologna and the Geneva Human Rights Platform, led an engaging discussion on the role of Local and Regional Governments (LRGs) in human rights implementation. The event, organized as a &hellip;","og_url":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/","og_site_name":"Global Cities Hub","article_published_time":"2025-03-19T10:46:00+00:00","article_modified_time":"2025-03-24T10:46:27+00:00","og_image":[{"width":786,"height":524,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/03\/vignette-2.png","type":"image\/png"}],"author":"root_new","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"Escrito por":"root_new","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/"},"author":{"name":"root_new","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"Localizing multilateralism: the role of local and regional governments in advancing human rights and SDGs","datePublished":"2025-03-19T10:46:00+00:00","dateModified":"2025-03-24T10:46:27+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/"},"wordCount":557,"publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/03\/vignette-2.png","keywords":["cities","human rights","localization","localizing","multilateralism","SDGs"],"articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/","url":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/","name":"Localizaci\u00f3n del multilateralismo: el papel de los gobiernos locales y regionales en la promoci\u00f3n de los derechos humanos y los ODS - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/03\/vignette-2.png","datePublished":"2025-03-19T10:46:00+00:00","dateModified":"2025-03-24T10:46:27+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/localizing-multilateralism-the-role-of-local-and-regional-governments-in-advancing-human-rights-and-sdgs\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/03\/vignette-2.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2025\/03\/vignette-2.png","width":786,"height":524},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/es\/#website","url":"https:\/\/globalcitieshub.org\/es\/","name":"Global Cities Hub","description":"Conectar a los gobiernos locales y regionales con las Naciones Unidas y otras organizaciones internacionales.","publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/es\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"raiz_nueva","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","url":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/plugins\/townhub-add-ons\/assets\/images\/avatar.jpg","caption":"root_new"},"sameAs":["http:\/\/gch.dev-bulbera.com"],"url":"https:\/\/globalcitieshub.org\/es\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/23657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/comments?post=23657"}],"version-history":[{"count":1,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/23657\/revisions"}],"predecessor-version":[{"id":23658,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/23657\/revisions\/23658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media\/23554"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media?parent=23657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/categories?post=23657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/tags?post=23657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}