{"id":18600,"date":"2023-06-08T15:40:35","date_gmt":"2023-06-08T13:40:35","guid":{"rendered":"https:\/\/www.genevacitieshub.org\/?p=18600"},"modified":"2023-06-12T15:40:47","modified_gmt":"2023-06-12T13:40:47","slug":"cities-also-work-on-human-rights","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/","title":{"rendered":"Las ciudades tambi\u00e9n trabajan en derechos humanos"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El 8 de junio, durante <a href=\"https:\/\/unhabitat.org\/governance\/un-habitat-assembly\/second-session-2023\" target=\"_blank\" rel=\"noreferrer noopener\">la 2<sup>nd<\/sup> Asamblea de H\u00e1bitat de la ONU<\/a> (Nairobi), el Geneva Cities Hub organiz\u00f3 un acto paralelo en colaboraci\u00f3n con miembros del <a href=\"https:\/\/www.genevacitieshub.org\/en\/launch-of-the-coalition-lrgs-in-upr\/\">Coalici\u00f3n para los GLR en el EPU<\/a> (ONU H\u00e1bitat, Friedrich Ebert Stiftung, OACDH, UPR Info, Plataforma de Derechos Humanos de Ginebra). El objetivo era hacer hincapi\u00e9 en que el Examen Peri\u00f3dico Universal (EPU), un mecanismo del Consejo de Derechos Humanos de la ONU, tambi\u00e9n debe ser utilizado por los gobiernos locales y regionales (GLR) para mostrar su trabajo sobre los ODS y los derechos humanos. M\u00e1s informaci\u00f3n sobre c\u00f3mo los GLR pueden contribuir al EPU <a href=\"https:\/\/www.genevacitieshub.org\/en\/the-coalition-for-local-and-regional-governments-in-upr-publishes-upr-tips-for-lrgs\/\">aqu\u00ed<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada d\u00eda, los GLR localizan los Objetivos de Desarrollo Sostenible (ODS) y trabajan en materia de vivienda, agua y saneamiento, espacios p\u00fablicos seguros, inclusi\u00f3n social, igualdad de g\u00e9nero, etc. Aunque los GLR se basan expl\u00edcitamente en los ODS como marco de referencia para orientar sus pol\u00edticas y programas, parece haber menos conciencia sobre el hecho de que los GLR tambi\u00e9n hacen realidad los derechos humanos. Mediante la localizaci\u00f3n de los ODS y el cumplimiento de los derechos humanos, los GLR contribuyen al cumplimiento de las obligaciones internacionales de los Estados. En consecuencia, los GLR deber\u00edan adquirir m\u00e1s visibilidad internacional y mostrar su crucial trabajo diario. Cada vez m\u00e1s GLR presentan Ex\u00e1menes Locales Voluntarios (VLR) que demuestran su avance en los ODS. Sin embargo, los GLR podr\u00edan ganar m\u00e1s visibilidad internacional por su trabajo en los ODS y los derechos humanos a trav\u00e9s del EPU. Los GLR tienen mucho que ganar participando en el EPU, incluida una mejor comprensi\u00f3n de su posici\u00f3n en relaci\u00f3n con los ODS y los derechos humanos (que est\u00e1n estrechamente interrelacionados), la oportunidad de recopilar datos y reforzar el di\u00e1logo con la administraci\u00f3n central sobre cuestiones pertinentes que suelen plantearse durante el EPU (por ejemplo, vivienda, educaci\u00f3n, salud, no discriminaci\u00f3n, igualdad de g\u00e9nero, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el acto, representantes municipales de Bonn (Alemania) y Nakuru (Kenia) demostraron su firme compromiso con los ODS y los derechos humanos. <strong>Melanie Grabowy<\/strong>, <strong>Teniente de alcalde, Bonn<\/strong>, habl\u00f3 de los dos VLR presentados por Bonn y de su relaci\u00f3n con los derechos humanos. Mencion\u00f3, por ejemplo, la prohibici\u00f3n del trabajo infantil, la asistencia a los refugiados, la provisi\u00f3n de viviendas adecuadas y asequibles, la igualdad de g\u00e9nero y la participaci\u00f3n de los habitantes de las ciudades en los asuntos p\u00fablicos. Subray\u00f3 que el proceso de VLR desempe\u00f1\u00f3 un papel muy importante en la percepci\u00f3n de Bonn a nivel internacional y facilit\u00f3 que su ciudad fuera escuchada. A\u00f1adi\u00f3 que <em>\"hoy en d\u00eda existe una clara demanda por parte de los municipios de participar en los procesos internacionales de elaboraci\u00f3n de pol\u00edticas<\/em>\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nakuru, la 4<sup>th<\/sup> ciudad de Kenia, se est\u00e1 urbanizando muy r\u00e1pidamente. Por ello, se est\u00e1n haciendo esfuerzos para garantizar que su desarrollo sea sostenible y que Nakuru se convierta en una \"ciudad justa\" para todos sus residentes, incluidos los \"pobres urbanos\", a menudo dejados de lado, en las zonas informales de la ciudad. Recientemente se ha embarcado en un proceso de VLR, <strong>Gitau Thabanja, Administrador Municipal, Nakuru<\/strong>En respuesta a una pregunta sobre los beneficios de la participaci\u00f3n de Nakuru en el EPU, afirm\u00f3 que \"la participaci\u00f3n de Nakuru en el EPU ha sido muy positiva\". En respuesta a una pregunta sobre los beneficios de la participaci\u00f3n de Nakuru en el EPU, afirm\u00f3 que \"<em>puede ofrecer la oportunidad de compararse con otros y buscar las mejores pr\u00e1cticas en otros lugares, para no reinventar la rueda<\/em>\".&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Robert Lewis-Lettington, Jefe de la Secci\u00f3n de Tierra, Vivienda y Refugio, ONU-H\u00e1bitat<\/strong>El Sr. Lewis-Lettington se refiri\u00f3 a los or\u00edgenes del mandato de ONU-H\u00e1bitat, profundamente arraigado en los derechos humanos, en particular en lo que se refiere a la vivienda, el agua y el saneamiento. Adem\u00e1s, Robert Lewis-Lettington tambi\u00e9n hizo hincapi\u00e9 en que todas las entidades de la ONU est\u00e1n obligadas por la Carta de las Naciones Unidas y sus 3 pilares, a saber, la paz y la seguridad, el desarrollo y los derechos humanos. Por lo tanto, es relevante para ONU H\u00e1bitat comprometerse con el EPU, un mecanismo de derechos humanos de la ONU, que aborda muchos temas que se encuentran en el coraz\u00f3n del mandato de ONU H\u00e1bitat.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El debate con el p\u00fablico fue muy animado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>preguntas relativas a la necesidad de que los urbanistas tengan en cuenta las necesidades de las personas mayores y las personas con discapacidad en materia de vivienda,&nbsp;<\/li>\n\n\n\n<li>el compromiso de un representante del Estado de reforzar los canales de di\u00e1logo con las ciudades,<\/li>\n\n\n\n<li>un interesante debate sobre los v\u00ednculos entre los ODS y los derechos humanos y el car\u00e1cter voluntario de las recomendaciones del EPU (que pueden aceptarse o simplemente \"tomarse nota\"), cuando los derechos humanos son en realidad obligaciones jur\u00eddicamente vinculantes para los Estados,<\/li>\n\n\n\n<li>el intercambio de experiencias de los representantes de otras ciudades sobre c\u00f3mo despliegan los programas de derechos humanos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Como conclusi\u00f3n, se hizo hincapi\u00e9 en que, independientemente de si hablamos de ODS o de derechos humanos, las ciudades se preocupan por su poblaci\u00f3n y atienden sus necesidades y aspiraciones, independientemente del marco internacional utilizado. Comprometerse a nivel internacional para mostrar ese trabajo, por ejemplo a trav\u00e9s de un Examen Peri\u00f3dico Universal, es importante para las ciudades, tanto en t\u00e9rminos de resultado (visi\u00f3n general de la situaci\u00f3n de una ciudad en cuanto a la aplicaci\u00f3n de los ODS), como en t\u00e9rminos de proceso (coordinaci\u00f3n entre los distintos servicios municipales, di\u00e1logo con la administraci\u00f3n nacional, conexi\u00f3n con otras ciudades y aprendizaje de ellas, etc.). La participaci\u00f3n en el EPU proporcionar\u00eda los mismos beneficios a los GLR y el GCH y sus socios de coalici\u00f3n seguir\u00e1n apoyando su participaci\u00f3n en este importante mecanismo de derechos humanos.<\/p>","protected":false},"excerpt":{"rendered":"<p>El 8 de junio, durante la 2\u00aa Asamblea de las Naciones Unidas para el H\u00e1bitat (Nairobi), el Geneva Cities Hub organiz\u00f3 un evento paralelo en colaboraci\u00f3n con los miembros de la Coalici\u00f3n para los GLR en el EPU (ONU H\u00e1bitat, Friedrich Ebert Stiftung, OACDH, UPR Info, Geneva Human Rights Platform). El objetivo era destacar que el Examen Peri\u00f3dico Universal (EPU), un mecanismo de ... <\/p>","protected":false},"author":1,"featured_media":18603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cities also work on human rights - Global Cities Hub<\/title>\n<meta name=\"description\" content=\"Cities also work on human rights. Let\u2019s make sure they contribute to the UN Universal Periodic Review to better fulfill the SDGs\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cities also work on human rights - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"Cities also work on human rights. Let\u2019s make sure they contribute to the UN Universal Periodic Review to better fulfill the SDGs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-08T13:40:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T13:40:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/06\/News-5.png\" \/>\n\t<meta property=\"og:image:width\" content=\"786\" \/>\n\t<meta property=\"og:image:height\" content=\"524\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Global Cities Hub\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Global Cities Hub\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/\"},\"author\":{\"name\":\"Global Cities Hub\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"Cities also work on human rights\",\"datePublished\":\"2023-06-08T13:40:35+00:00\",\"dateModified\":\"2023-06-12T13:40:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/\"},\"wordCount\":821,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/News-5.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/\",\"name\":\"Cities also work on human rights - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/News-5.png\",\"datePublished\":\"2023-06-08T13:40:35+00:00\",\"dateModified\":\"2023-06-12T13:40:47+00:00\",\"description\":\"Cities also work on human rights. Let\u2019s make sure they contribute to the UN Universal Periodic Review to better fulfill the SDGs\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/cities-also-work-on-human-rights\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/News-5.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/News-5.png\",\"width\":786,\"height\":524},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"Global Cities Hub\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"caption\":\"Global Cities Hub\"},\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las ciudades tambi\u00e9n trabajan por los derechos humanos - Global Cities Hub","description":"Las ciudades tambi\u00e9n trabajan en el \u00e1mbito de los derechos humanos. Asegur\u00e9monos de que contribuyen al Examen Peri\u00f3dico Universal de la ONU para cumplir mejor los ODS.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/","og_locale":"es_ES","og_type":"article","og_title":"Cities also work on human rights - Global Cities Hub","og_description":"Cities also work on human rights. Let\u2019s make sure they contribute to the UN Universal Periodic Review to better fulfill the SDGs","og_url":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/","og_site_name":"Global Cities Hub","article_published_time":"2023-06-08T13:40:35+00:00","article_modified_time":"2023-06-12T13:40:47+00:00","og_image":[{"width":786,"height":524,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/06\/News-5.png","type":"image\/png"}],"author":"Global Cities Hub","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"Escrito por":"Global Cities Hub","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/"},"author":{"name":"Global Cities Hub","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"Cities also work on human rights","datePublished":"2023-06-08T13:40:35+00:00","dateModified":"2023-06-12T13:40:47+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/"},"wordCount":821,"publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/06\/News-5.png","articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/","url":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/","name":"Las ciudades tambi\u00e9n trabajan por los derechos humanos - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/06\/News-5.png","datePublished":"2023-06-08T13:40:35+00:00","dateModified":"2023-06-12T13:40:47+00:00","description":"Las ciudades tambi\u00e9n trabajan en el \u00e1mbito de los derechos humanos. Asegur\u00e9monos de que contribuyen al Examen Peri\u00f3dico Universal de la ONU para cumplir mejor los ODS.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/cities-also-work-on-human-rights\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/06\/News-5.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/06\/News-5.png","width":786,"height":524},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/es\/#website","url":"https:\/\/globalcitieshub.org\/es\/","name":"Global Cities Hub","description":"Conectar a los gobiernos locales y regionales con las Naciones Unidas y otras organizaciones internacionales.","publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/es\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"Global Cities Hub","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","caption":"Global Cities Hub"},"url":"https:\/\/globalcitieshub.org\/es\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/18600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/comments?post=18600"}],"version-history":[{"count":2,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/18600\/revisions"}],"predecessor-version":[{"id":18602,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/18600\/revisions\/18602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media\/18603"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media?parent=18600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/categories?post=18600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/tags?post=18600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}