{"id":10347,"date":"2019-06-09T14:07:00","date_gmt":"2019-06-09T14:07:00","guid":{"rendered":"https:\/\/gch.dev-bulbera.com\/?p=10347"},"modified":"2021-03-10T14:08:25","modified_gmt":"2021-03-10T14:08:25","slug":"experts-discuss-human-rights-at-the-city-level","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/","title":{"rendered":"LOS EXPERTOS DEBATEN SOBRE LOS DERECHOS HUMANOS EN LAS CIUDADES"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En una conferencia en l\u00ednea coorganizada por el&nbsp;<a href=\"https:\/\/geneva-academy.ch\/geneva-humanrights-platform\" target=\"_blank\" rel=\"noreferrer noopener\">Plataforma de Derechos Humanos de Ginebra<\/a>,&nbsp;<a href=\"https:\/\/unhabitat.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">ONU-H\u00e1bitat<\/a>El&nbsp;<a href=\"http:\/\/www.ohchr.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Oficina del Alto Comisionado de las Naciones Unidas para los Derechos Humanos<\/a>&nbsp;y el&nbsp;<a href=\"https:\/\/www.genevacitieshub.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Centro de Ciudades de Ginebra<\/a>En el marco de la conferencia, unos 60 expertos -activistas locales, acad\u00e9micos y representantes de las autoridades locales, la sociedad civil, las organizaciones internacionales y el sector privado- intercambiaron ideas sobre las mejores pr\u00e1cticas para basar el desarrollo de las ciudades en un marco de derechos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;El papel del gobierno local en la promoci\u00f3n y protecci\u00f3n de los derechos humanos&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los participantes en la reuni\u00f3n destacaron la importancia de los gobiernos locales para promover y proteger los derechos humanos a nivel local.  Aunque las ciudades y los gobiernos locales no est\u00e1n representados actualmente en foros internacionales como la ONU, su voz podr\u00eda llegar a trav\u00e9s de otros actores como ONU-H\u00e1bitat o el Centro de Ciudades de Ginebra\", explica Kamelia Kemileva, directora a.i. del Centro de Ciudades de Ginebra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la reuni\u00f3n tambi\u00e9n se debatieron las categor\u00edas de vulnerabilidad a nivel de ciudad, como las personas mayores y las personas con discapacidad, pero tambi\u00e9n las personas que viven con el VIH\/SIDA, los inmigrantes y las personas LGBTQI.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para algunos de estos grupos, su propia \"ilegalidad\" o \"criminalidad\" es una barrera fundamental para la inclusi\u00f3n en las ciudades, los marcos de derechos de vivienda y su acceso a los servicios y derechos b\u00e1sicos. La crisis de COVID-19 no hace m\u00e1s que exacerbar estas desigualdades, empujando a los miembros de estos grupos a encontrar soluciones informales, que al final son contraproducentes para sus intenciones y necesidades\", explica Kamelia Kemileva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los participantes tambi\u00e9n reiteraron que los derechos humanos no son aspiraciones ni objetivos sociales, sino normas jur\u00eddicas que pueden y deben incorporarse a la arquitectura legal de los distintos sistemas: vivienda, sanidad p\u00fablica, transporte, etc. Destacaron que los derechos s\u00f3lo pueden respetarse y aplicarse plenamente si se incorporan a las normas jur\u00eddicas, sobre todo a nivel local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;Hacia ciudades inclusivas para todos&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta reuni\u00f3n es la primera de una serie m\u00e1s larga cuyo objetivo es elaborar documentos operativos para los gobiernos locales, los profesionales y los responsables de la toma de decisiones a nivel de las ciudades, as\u00ed como los gobiernos nacionales interesados en las cuestiones de gobernanza local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos documentos proporcionar\u00e1n orientaci\u00f3n sobre c\u00f3mo traducir las normas de derechos humanos a nivel de la ciudad, especialmente en relaci\u00f3n con el g\u00e9nero; la inclusi\u00f3n de los ni\u00f1os y los j\u00f3venes; la inclusi\u00f3n de las personas mayores y las personas con discapacidad; as\u00ed como la inclusi\u00f3n de los grupos en riesgo de marginaci\u00f3n como los refugiados o los pueblos ind\u00edgenas, pero tambi\u00e9n dentro de los contextos de la ciudad los grupos que son menos mencionados pero tambi\u00e9n vulnerables como los trabajadores sexuales y los consumidores de drogas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta reuni\u00f3n del grupo de expertos es la primera de una serie sobre ciudades inclusivas. Por supuesto, tenemos un motivo ego\u00edsta: queremos recoger los cerebros de los mejores pensadores y profesionales de los derechos humanos y conseguir que nos digan c\u00f3mo podemos integrar un enfoque basado en los derechos humanos en nuestro trabajo a trav\u00e9s de estos \u00e1mbitos de cambio y las \u00e1reas de resultados de nuestro Plan Estrat\u00e9gico. El compromiso no termina aqu\u00ed, sino que empieza aqu\u00ed. Tambi\u00e9n queremos reunir a este grupo como una comunidad de pr\u00e1ctica m\u00e1s amplia para que trabaje con nosotros mientras desarrollamos algunas de las ideas para convertirlas en principios rectores, indicadores clave, herramientas, metodolog\u00eda, etc., y aplicarlas en los pr\u00f3ximos tres a\u00f1os\", subraya Shipra Narang Suri, Jefa de la Subdivisi\u00f3n de Pr\u00e1cticas Urbanas de ONU-H\u00e1bitat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es fundamental garantizar que el marco internacional de derechos humanos y las decisiones adoptadas por los organismos de derechos humanos con sede en Ginebra se apliquen a nivel local. Por eso estamos encantados de participar en este proyecto, ya que representa una nueva dimensi\u00f3n para nosotros que incluye a los gobiernos locales. Esto puede ayudar a tender un puente entre Ginebra y el terreno\", explica Felix Kirchmeier, Director Ejecutivo de la Plataforma de Derechos Humanos de Ginebra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Geneva Cities Hub fomenta este di\u00e1logo y facilita las relaciones entre las organizaciones de Ginebra y los gobiernos locales\", subraya Kamelia Kemileva.<\/p>","protected":false},"excerpt":{"rendered":"<p>En una conferencia en l\u00ednea organizada conjuntamente por la Plataforma de Derechos Humanos de Ginebra, ONU-H\u00e1bitat, la Oficina del Alto Comisionado de las Naciones Unidas para los Derechos Humanos y el Geneva Cities Hub, unos 60 expertos -activistas locales, acad\u00e9micos, as\u00ed como representantes de las autoridades locales, la sociedad civil, organizaciones internacionales y el sector privado- intercambiaron en torno a las mejores pr\u00e1cticas para fundamentar el desarrollo de las ciudades ... <\/p>","protected":false},"author":1,"featured_media":10349,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXPERTS DISCUSS HUMAN RIGHTS AT THE CITY LEVEL - Global Cities Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXPERTS DISCUSS HUMAN RIGHTS AT THE CITY LEVEL - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"In an online conference co-organized by the&nbsp;Geneva Human Rights Platform,&nbsp;UN-Habitat, the&nbsp;Office of the UN High Commissioner for Human Rights&nbsp;and the&nbsp;Geneva Cities Hub, &nbsp;around 60 experts \u2013 local activists, academics as well as &nbsp;representatives from local authorities, civil society, international &nbsp;organizations and the private sector \u2013 exchanged around best practices &nbsp;to ground the development of cities &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-09T14:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-10T14:08:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2019\/06\/ezgif.com-gif-maker-15.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Global Cities Hub\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Global Cities Hub\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/\"},\"author\":{\"name\":\"Global Cities Hub\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"EXPERTS DISCUSS HUMAN RIGHTS AT THE CITY LEVEL\",\"datePublished\":\"2019-06-09T14:07:00+00:00\",\"dateModified\":\"2021-03-10T14:08:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/\"},\"wordCount\":666,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ezgif.com-gif-maker-15.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/\",\"name\":\"EXPERTS DISCUSS HUMAN RIGHTS AT THE CITY LEVEL - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ezgif.com-gif-maker-15.png\",\"datePublished\":\"2019-06-09T14:07:00+00:00\",\"dateModified\":\"2021-03-10T14:08:25+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/experts-discuss-human-rights-at-the-city-level\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ezgif.com-gif-maker-15.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/ezgif.com-gif-maker-15.png\",\"width\":800,\"height\":800},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"Global Cities Hub\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"caption\":\"Global Cities Hub\"},\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXPERTOS DISCUTEN SOBRE LOS DERECHOS HUMANOS A NIVEL CIUDADANO - Global Cities Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/","og_locale":"es_ES","og_type":"article","og_title":"EXPERTS DISCUSS HUMAN RIGHTS AT THE CITY LEVEL - Global Cities Hub","og_description":"In an online conference co-organized by the&nbsp;Geneva Human Rights Platform,&nbsp;UN-Habitat, the&nbsp;Office of the UN High Commissioner for Human Rights&nbsp;and the&nbsp;Geneva Cities Hub, &nbsp;around 60 experts \u2013 local activists, academics as well as &nbsp;representatives from local authorities, civil society, international &nbsp;organizations and the private sector \u2013 exchanged around best practices &nbsp;to ground the development of cities &hellip;","og_url":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/","og_site_name":"Global Cities Hub","article_published_time":"2019-06-09T14:07:00+00:00","article_modified_time":"2021-03-10T14:08:25+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2019\/06\/ezgif.com-gif-maker-15.png","type":"image\/png"}],"author":"Global Cities Hub","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"Escrito por":"Global Cities Hub","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/"},"author":{"name":"Global Cities Hub","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"EXPERTS DISCUSS HUMAN RIGHTS AT THE CITY LEVEL","datePublished":"2019-06-09T14:07:00+00:00","dateModified":"2021-03-10T14:08:25+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/"},"wordCount":666,"publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2019\/06\/ezgif.com-gif-maker-15.png","articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/","url":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/","name":"EXPERTOS DISCUTEN SOBRE LOS DERECHOS HUMANOS A NIVEL CIUDADANO - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2019\/06\/ezgif.com-gif-maker-15.png","datePublished":"2019-06-09T14:07:00+00:00","dateModified":"2021-03-10T14:08:25+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/experts-discuss-human-rights-at-the-city-level\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2019\/06\/ezgif.com-gif-maker-15.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2019\/06\/ezgif.com-gif-maker-15.png","width":800,"height":800},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/es\/#website","url":"https:\/\/globalcitieshub.org\/es\/","name":"Global Cities Hub","description":"Conectar a los gobiernos locales y regionales con las Naciones Unidas y otras organizaciones internacionales.","publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/es\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"Global Cities Hub","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","caption":"Global Cities Hub"},"url":"https:\/\/globalcitieshub.org\/es\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/10347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/comments?post=10347"}],"version-history":[{"count":1,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/10347\/revisions"}],"predecessor-version":[{"id":10348,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/10347\/revisions\/10348"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media\/10349"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media?parent=10347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/categories?post=10347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/tags?post=10347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}