{"id":10306,"date":"2020-08-25T13:27:00","date_gmt":"2020-08-25T13:27:00","guid":{"rendered":"https:\/\/gch.dev-bulbera.com\/?p=10306"},"modified":"2021-03-10T14:59:15","modified_gmt":"2021-03-10T14:59:15","slug":"the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva","status":"publish","type":"post","link":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/","title":{"rendered":"EL HUB DE CIUDADES DE GINEBRA: UNA NUEVA INICIATIVA PARA REFORZAR LA PRESENCIA DE LOS ACTORES URBANOS EN LA GINEBRA INTERNACIONAL"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10306\" class=\"elementor elementor-10306\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1101b4e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1101b4e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7242b0c5\" data-id=\"7242b0c5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5591c435 elementor-widget elementor-widget-text-editor\" data-id=\"5591c435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\">El Sr. Sami Kanaan, alcalde de la ciudad de Ginebra, present\u00f3 el Centro de Ciudades de Ginebra, una nueva plataforma centrada en los actores y problemas urbanos. Creado por la Ciudad de Ginebra y el Cant\u00f3n de Ginebra con el apoyo de la Confederaci\u00f3n Suiza, el Centro de Ciudades de Ginebra promover\u00e1 el debate y la cooperaci\u00f3n sobre cuestiones urbanas dentro de la comunidad internacional de Ginebra y establecer\u00e1 v\u00ednculos m\u00e1s estrechos entre las ciudades, las redes de ciudades y los actores de Ginebra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su discurso de apertura, Tatiana Valovaya, Directora General de la&nbsp;<a href=\"https:\/\/www.ungeneva.org\/en\" target=\"_blank\" rel=\"noreferrer noopener\">Oficina de las Naciones Unidas en Ginebra (ONUG)<\/a>La Sra. Kolping, de la Universidad de California, subray\u00f3 que \"para las Naciones Unidas, el di\u00e1logo con las comunidades urbanas y las ciudades es crucial, ya que desempe\u00f1an un papel cada vez m\u00e1s importante en todos los aspectos de nuestra vida y en la pol\u00edtica mundial\". Record\u00f3 que las autoridades locales y las comunidades urbanas son las primeras en responder a las crisis mundiales, como la pandemia de coronavirus, y que son fundamentales para alcanzar todos los ODS. La Sra. Valovaya destac\u00f3 que \"el multilateralismo moderno debe ser inclusivo. Los nuevos actores, incluidas las ciudades, tienen un papel clave que desempe\u00f1ar. Cuando tomamos decisiones, tenemos que consultar y comunicarnos con las ciudades\". Concluy\u00f3 diciendo que \"en este sentido, el Geneva Cities Hub puede contribuir a un multilateralismo moderno e inclusivo. En nombre de la ONUG estamos dispuestos a colaborar estrechamente\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u200b<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Sr. Kanaan acogi\u00f3 con satisfacci\u00f3n el apoyo de la ONUG al Geneva Cities Hub y a\u00f1adi\u00f3 que \"aunque las ciudades no redactan leyes, est\u00e1n a la vanguardia de los problemas de la poblaci\u00f3n, como el cambio clim\u00e1tico, las cuestiones sociales, la migraci\u00f3n y ahora la pandemia. Los Estados desempe\u00f1an un papel crucial, pero no pueden resolver estos problemas globales por s\u00ed solos. Los gobiernos locales y sus redes son socios cruciales para identificar los retos y proponer soluciones innovadoras y concretas ancladas en las comunidades locales\". Como ejemplos, se refiri\u00f3 al apoyo solidario internacional de ciudad a ciudad en favor de Beirut movilizado por la Asociaci\u00f3n Internacional de Alcaldes Franc\u00f3fonos (AIMF) y por el Grupo de Trabajo de CGLU presidido por Ginebra para la prevenci\u00f3n y gesti\u00f3n territorial de las crisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En nombre de Suiza, el Embajador Yannick Roulin expres\u00f3 su apoyo a la nueva plataforma, que enriquece el panorama del ecosistema internacional de Ginebra con una dimensi\u00f3n urbana. \"Como Gobierno, consideramos crucial implicar mejor la perspectiva de las ciudades en nuestro trabajo, por su experiencia, su conocimiento del terreno y su capacidad de aplicaci\u00f3n. Reconocer esto no es reducir la importancia de los Estados, sino asegurar que nuestro trabajo sea m\u00e1s efectivo y relevante\", dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje de v\u00eddeo, la Sra. Souad Abderrahim, alcaldesa de la ciudad de T\u00fanez y miembro del Bur\u00f3 Ejecutivo de la AIMF, destac\u00f3 c\u00f3mo las crisis del siglo XXI -desde el cambio clim\u00e1tico hasta el actual Covid 19- han puesto a los alcaldes y a las autoridades locales en primera l\u00ednea. Subray\u00f3 la importancia de que las organizaciones internacionales presten apoyo a las asociaciones de autoridades locales y confi\u00f3 en que el Geneva Cities Hub contribuya a reforzar esta cooperaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n tuvo lugar un panel moderado por el Sr. Kanaan. La Sra. Isabel Mestres Mesa, Directora de Asuntos P\u00fablicos de&nbsp;<a href=\"https:\/\/citycancerchallenge.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Reto del C\u00e1ncer en la Ciudad<\/a>La Sra. Kolman, explic\u00f3 los motivos por los que la organizaci\u00f3n se centr\u00f3 en la ciudad. Dado que la atenci\u00f3n al c\u00e1ncer es compleja y est\u00e1 relacionada con todo el sistema sanitario, su organizaci\u00f3n eligi\u00f3 un punto de partida a nivel de ciudad. Esto permite a City Cancer Challenge aprovechar la innovaci\u00f3n, la agilidad y el liderazgo necesarios para crear conjuntamente soluciones duraderas, que luego pueden ampliarse a escala nacional y transferirse a otras ciudades. \"Por eso las ciudades deber\u00edan desempe\u00f1ar un papel m\u00e1s importante en el di\u00e1logo sobre la salud mundial\", concluy\u00f3. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Achim Wennmann, Coordinador Ejecutivo de la&nbsp;<a href=\"https:\/\/www.gpplatform.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Plataforma de Ginebra para la consolidaci\u00f3n de la paz<\/a>&nbsp;e investigador principal del Instituto de Postgrado, se\u00f1al\u00f3 la relevancia del Geneva Cities Hub como una nueva iniciativa que tiene en cuenta a las ciudades como actores, pero tambi\u00e9n a las ciudades como espacios en los que ocurren cosas -como guerras, desastres y protestas- y que son gestionadas por las administraciones municipales y otros actores urbanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, la Sra. Paola Deda, Directora de la Divisi\u00f3n de Bosques, Tierras y Vivienda de la Comisi\u00f3n Econ\u00f3mica de las Naciones Unidas para Europa (CEPE), destac\u00f3 la importancia de una mejor vinculaci\u00f3n entre las decisiones y orientaciones elaboradas por los gobiernos a nivel internacional y la aplicaci\u00f3n por parte de los gobiernos locales a nivel operativo. Subray\u00f3 el papel de los alcaldes, que son quienes tienen las manos y el pulso de la gente. Sus voces no son alternativas sino complementarias a las de los gobiernos centrales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El p\u00fablico que particip\u00f3 en el debate acogi\u00f3 con satisfacci\u00f3n la creaci\u00f3n del Hub de Ciudades de Ginebra, que percibi\u00f3 como un complemento \u00fatil de la Ginebra Internacional. Varios participantes se refirieron al pr\u00f3ximo gran evento de las ciudades de Ginebra: el&nbsp;<a href=\"https:\/\/forumofmayors.unece.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Foro de Alcaldes de la CEPE<\/a>&nbsp;el 6 de octubre de 2020. El Foro estar\u00e1 precedido por una&nbsp;<a href=\"https:\/\/www.unece.org\/housing\/sdg11day2020.html\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00eda dedicado al ODS11: \"Apoyar las acciones de las ciudades para un futuro resiliente\"<\/a>&nbsp;con la participaci\u00f3n de redes de ciudades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b82dcd4 elementor-widget elementor-widget-video\" data-id=\"b82dcd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=miQUWjsKNK4&amp;t=1s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El Sr. Sami Kanaan, alcalde de la ciudad de Ginebra, present\u00f3 el Centro de Ciudades de Ginebra, una nueva plataforma centrada en los actores y problemas urbanos. Creado por la Ciudad de Ginebra y el Cant\u00f3n de Ginebra con el apoyo de la Confederaci\u00f3n Suiza, el Geneva Cities Hub promover\u00e1 el debate y la cooperaci\u00f3n sobre cuestiones urbanas dentro de la... <\/p>","protected":false},"author":1,"featured_media":10318,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>THE GENEVA CITIES HUB: A NEW INITIATIVE TO STRENGTHEN THE PRESENCE OF URBAN ACTORS IN INTERNATIONAL GENEVA - Global Cities Hub<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"THE GENEVA CITIES HUB: A NEW INITIATIVE TO STRENGTHEN THE PRESENCE OF URBAN ACTORS IN INTERNATIONAL GENEVA - Global Cities Hub\" \/>\n<meta property=\"og:description\" content=\"Mr. Sami Kanaan, Mayor of the City of Geneva, presented the Geneva Cities Hub, a new platform focusing on urban actors and issues. Created by the City of Geneva and the Canton of Geneva with the support of the Swiss Confederation, the Geneva Cities Hub will promote discussion and cooperation on urban issues within the &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/\" \/>\n<meta property=\"og:site_name\" content=\"Global Cities Hub\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-25T13:27:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-10T14:59:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2021\/03\/ezgif.com-gif-maker-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1315\" \/>\n\t<meta property=\"og:image:height\" content=\"915\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Global Cities Hub\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:site\" content=\"@genevacitieshub\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Global Cities Hub\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/\"},\"author\":{\"name\":\"Global Cities Hub\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\"},\"headline\":\"THE GENEVA CITIES HUB: A NEW INITIATIVE TO STRENGTHEN THE PRESENCE OF URBAN ACTORS IN INTERNATIONAL GENEVA\",\"datePublished\":\"2020-08-25T13:27:00+00:00\",\"dateModified\":\"2021-03-10T14:59:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/\"},\"wordCount\":813,\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ezgif.com-gif-maker-6.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/\",\"name\":\"THE GENEVA CITIES HUB: A NEW INITIATIVE TO STRENGTHEN THE PRESENCE OF URBAN ACTORS IN INTERNATIONAL GENEVA - Global Cities Hub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ezgif.com-gif-maker-6.jpg\",\"datePublished\":\"2020-08-25T13:27:00+00:00\",\"dateModified\":\"2021-03-10T14:59:15+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ezgif.com-gif-maker-6.jpg\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ezgif.com-gif-maker-6.jpg\",\"width\":1315,\"height\":915},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"name\":\"Global Cities Hub\",\"description\":\"Connecting local and regional governments to the United Nations and other  international organizations\",\"publisher\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#organization\",\"name\":\"Global Cities Hub\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"width\":2544,\"height\":1446,\"caption\":\"Global Cities Hub\"},\"image\":{\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/genevacitieshub\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/#\\\/schema\\\/person\\\/507d9e6bfa91593e51e4b24f8c3efc42\",\"name\":\"Global Cities Hub\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"contentUrl\":\"https:\\\/\\\/globalcitieshub.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png\",\"caption\":\"Global Cities Hub\"},\"url\":\"https:\\\/\\\/globalcitieshub.org\\\/es\\\/author\\\/root_new\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EL GENEVA CITIES HUB: UNA NUEVA INICIATIVA PARA REFORZAR LA PRESENCIA DE LOS ACTORES URBANOS EN LA GINEBRA INTERNACIONAL - Global Cities Hub","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/","og_locale":"es_ES","og_type":"article","og_title":"THE GENEVA CITIES HUB: A NEW INITIATIVE TO STRENGTHEN THE PRESENCE OF URBAN ACTORS IN INTERNATIONAL GENEVA - Global Cities Hub","og_description":"Mr. Sami Kanaan, Mayor of the City of Geneva, presented the Geneva Cities Hub, a new platform focusing on urban actors and issues. Created by the City of Geneva and the Canton of Geneva with the support of the Swiss Confederation, the Geneva Cities Hub will promote discussion and cooperation on urban issues within the &hellip;","og_url":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/","og_site_name":"Global Cities Hub","article_published_time":"2020-08-25T13:27:00+00:00","article_modified_time":"2021-03-10T14:59:15+00:00","og_image":[{"width":1315,"height":915,"url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2021\/03\/ezgif.com-gif-maker-6.jpg","type":"image\/jpeg"}],"author":"Global Cities Hub","twitter_card":"summary_large_image","twitter_creator":"@genevacitieshub","twitter_site":"@genevacitieshub","twitter_misc":{"Escrito por":"Global Cities Hub","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/#article","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/"},"author":{"name":"Global Cities Hub","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42"},"headline":"THE GENEVA CITIES HUB: A NEW INITIATIVE TO STRENGTHEN THE PRESENCE OF URBAN ACTORS IN INTERNATIONAL GENEVA","datePublished":"2020-08-25T13:27:00+00:00","dateModified":"2021-03-10T14:59:15+00:00","mainEntityOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/"},"wordCount":813,"publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2021\/03\/ezgif.com-gif-maker-6.jpg","articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/","url":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/","name":"EL GENEVA CITIES HUB: UNA NUEVA INICIATIVA PARA REFORZAR LA PRESENCIA DE LOS ACTORES URBANOS EN LA GINEBRA INTERNACIONAL - Global Cities Hub","isPartOf":{"@id":"https:\/\/globalcitieshub.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/#primaryimage"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/#primaryimage"},"thumbnailUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2021\/03\/ezgif.com-gif-maker-6.jpg","datePublished":"2020-08-25T13:27:00+00:00","dateModified":"2021-03-10T14:59:15+00:00","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/the-geneva-cities-hub-a-new-initiative-to-strengthen-the-presence-of-urban-actors-in-international-geneva\/#primaryimage","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2021\/03\/ezgif.com-gif-maker-6.jpg","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2021\/03\/ezgif.com-gif-maker-6.jpg","width":1315,"height":915},{"@type":"WebSite","@id":"https:\/\/globalcitieshub.org\/es\/#website","url":"https:\/\/globalcitieshub.org\/es\/","name":"Global Cities Hub","description":"Conectar a los gobiernos locales y regionales con las Naciones Unidas y otras organizaciones internacionales.","publisher":{"@id":"https:\/\/globalcitieshub.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/globalcitieshub.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/globalcitieshub.org\/es\/#organization","name":"Global Cities Hub","url":"https:\/\/globalcitieshub.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","width":2544,"height":1446,"caption":"Global Cities Hub"},"image":{"@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/genevacitieshub"]},{"@type":"Person","@id":"https:\/\/globalcitieshub.org\/es\/#\/schema\/person\/507d9e6bfa91593e51e4b24f8c3efc42","name":"Global Cities Hub","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","url":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","contentUrl":"https:\/\/globalcitieshub.org\/wp-content\/uploads\/2023\/09\/230829_Logo_Global_Cities_Hub_Couleur_fond-blanc_RVB.png","caption":"Global Cities Hub"},"url":"https:\/\/globalcitieshub.org\/es\/author\/root_new\/"}]}},"_links":{"self":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/10306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/comments?post=10306"}],"version-history":[{"count":11,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/10306\/revisions"}],"predecessor-version":[{"id":10319,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/posts\/10306\/revisions\/10319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media\/10318"}],"wp:attachment":[{"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/media?parent=10306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/categories?post=10306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalcitieshub.org\/es\/wp-json\/wp\/v2\/tags?post=10306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}